{"id":12035,"date":"2025-07-07T11:00:30","date_gmt":"2025-07-07T14:00:30","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=12035"},"modified":"2025-07-07T11:00:32","modified_gmt":"2025-07-07T14:00:32","slug":"erro-grave-na-novela-eta-mundo-melhor-deixa-telespectadores-furiosos","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/erro-grave-na-novela-eta-mundo-melhor-deixa-telespectadores-furiosos\/","title":{"rendered":"Erro grave na novela \u201c\u00cata Mundo Melhor\u201d deixa telespectadores furiosos"},"content":{"rendered":"\n<p>Na semana passada, estreou a nova novela das seis da Globo, &#8220;\u00cata Mundo Melhor!&#8221;, continua\u00e7\u00e3o do fen\u00f4meno de audi\u00eancia &#8220;\u00cata Mundo Bom!&#8221;, exibida em 2016. Mas, apesar da boa repercuss\u00e3o da primeira semana, uma decis\u00e3o da trama j\u00e1 irritou muitos espectadores, principalmente os f\u00e3s da primeira novela.<\/p>\n\n\n\n<p>Alguns atores n\u00e3o voltaram para a sequ\u00eancia: um deles foi a mocinha da primeira, D\u00e9bora Nascimento, a int\u00e9rprete da Fil\u00f3, par rom\u00e2ntico do protagonista Candinho (S\u00e9rgio Guiz\u00e9). De acordo com a colunista Carla Bittencourt, do portal Leo Dias, as negocia\u00e7\u00f5es de D\u00e9bora com a emissora n\u00e3o avan\u00e7aram. A atriz \u00e9 mais um exemplo de profissional que n\u00e3o tem mais um contrato a longo prazo com a emissora, assinando apenas por obra.<\/p>\n\n\n\n<p>A solu\u00e7\u00e3o que o autor Walcyr Carrasco encontrou para justificar a decis\u00e3o: morte. Logo no primeiro cap\u00edtulo, Fil\u00f3 morre em um inc\u00eandio depois de tentar fugir com o amante Ernesto (Eriberto Le\u00e3o). <\/p>\n\n\n\n<p>A morte em si n\u00e3o foi um fator que irritou tanto os espectadores, mas, sim, a decis\u00e3o do autor que fazer a mocinha trair o protagonista, al\u00e9m de cenas em que v\u00e1rios personagens falam mal da mocinha. Espectadores argumentaram que essa decis\u00e3o n\u00e3o fez sentido com o desenvolvimento de Fil\u00f3 na novela original, em que ela enfrentou v\u00e1rios perigos para ficar com o mocinho. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">Esse plot que criaram pra suprir a aus\u00eancia da fil\u00f3 \u00e9 uma bosta, e n\u00e3o faz sentido algum ela decidir por vontade pr\u00f3pria  fugir com o ernesto se em \u00eata mundo bom, eles enfrentaram Deus e o mundo pra ficarem juntos. <a href=\"https:\/\/twitter.com\/hashtag\/EtaMundoMelhor?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#EtaMundoMelhor<\/a><a href=\"https:\/\/t.co\/Qhwb0adFTc\" target=\"_blank\">pic.twitter.com\/Qhwb0adFTc<\/a><\/p>&mdash; sarinhaa (@seccofavs) <a href=\"https:\/\/twitter.com\/seccofavs\/status\/1939797745067282590?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 30, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">Esse neg\u00f3cio da fil\u00f3 fugir com o Ernesto depois de casada com o candinho n\u00e3o entra na minha cabe\u00e7a <a href=\"https:\/\/twitter.com\/hashtag\/EtaMundoMelhor?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#EtaMundoMelhor<\/a> <a href=\"https:\/\/t.co\/emZEutKs5m\" target=\"_blank\">pic.twitter.com\/emZEutKs5m<\/a><\/p>&mdash; sarinhaa (@seccofavs) <a href=\"https:\/\/twitter.com\/seccofavs\/status\/1939794468485623851?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">June 30, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">&quot;Acho que a Fil\u00f3 nunca me amou&quot;<br><br>A mesma Fil\u00f3 que aceitou apanhar e sofrer abusos do Ernesto por que ele amea\u00e7ava matar o candido ou a fil\u00f3 que desistiu de uma heran\u00e7a milion\u00e1ria pra dizer a verdade sobre o filho ser do &quot;amor da vida dela&quot; candido? Canalhas!!!!! <a href=\"https:\/\/twitter.com\/hashtag\/EtaMundoMelhor?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#EtaMundoMelhor<\/a> <a href=\"https:\/\/t.co\/O1XRfKGFZL\" target=\"_blank\">pic.twitter.com\/O1XRfKGFZL<\/a><\/p>&mdash; Wally\ud83d\udc0d\u20dd\u20d2\u20e4 \ud83c\udf35\ud83c\udf19 (@reagewally) <a href=\"https:\/\/twitter.com\/reagewally\/status\/1939864596812083256?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 1, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">&#8220;\u00cata Mundo Melhor!&#8221;<\/h2>\n\n\n\n<p>Na continua\u00e7\u00e3o de &#8220;\u00cata Mundo Bom!&#8221;, a hist\u00f3ria come\u00e7a com o desaparecimento do filho de Candinho, que \u00e9 sequestrado pelo vil\u00e3o Ernesto. O beb\u00ea acaba nas m\u00e3os da vil\u00e3 Zulma (Helo\u00edsa P\u00e9riss\u00e9), que cuida de um orfanato onde as crian\u00e7as s\u00e3o mal tratadas e exploradas. Anos depois, Candinho continua \u00e0 procura do filho.<\/p>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/novela-das-seis-eta-mundo-melhor-e-acusada-de-racismo\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/06\/eta-mundo-bom.jpg\" data-src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/06\/eta-mundo-bom.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>TELEVIS\u00c3O<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Novela das seis &quot;\u00cata Mundo Melhor!&quot; \u00e9 acusada de racismo<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>A novela das seis &quot;\u00cata Mundo Melhor!&quot; est\u00e1 sendo acusada de racismo e anticiganismo por causa de cena envolvendo cigana do primeiro cap\u00edtulo.<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Leia mais<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/novela-das-seis-eta-mundo-melhor-e-acusada-de-racismo\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/06\/eta-mundo-bom.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Novela das seis &quot;\u00cata Mundo Melhor!&quot; \u00e9 acusada de racismo<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Leia mais<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Logo em seu primeiro cap\u00edtulo, &#8220;\u00cata Mundo Melhor!&#8221; tomou uma decis\u00e3o que deixou um gosto amargo na boca de muitos espectadores.<\/p>\n","protected":false},"author":6,"featured_media":11398,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"2","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"jnews_post_split":{"post_split":[{"template":"1","tag":"h2","numbering":"asc","mode":"normal","first":"0","enable_toc":"0","toc_type":"normal"}]},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/12035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=12035"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/12035\/revisions"}],"predecessor-version":[{"id":12044,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/12035\/revisions\/12044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/11398"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=12035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=12035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=12035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}