{"id":12037,"date":"2025-07-07T12:24:02","date_gmt":"2025-07-07T15:24:02","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=12037"},"modified":"2025-07-07T12:24:04","modified_gmt":"2025-07-07T15:24:04","slug":"novo-visitante-interestelar-acende-suspeitas-de-vida-alienigena-em-marte","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/novo-visitante-interestelar-acende-suspeitas-de-vida-alienigena-em-marte\/","title":{"rendered":"Novo visitante interestelar acende suspeitas de vida alien\u00edgena em Marte"},"content":{"rendered":"\n<p>Astr\u00f4nomos da Ag\u00eancia Espacial Europeia (ESA) anunciaram nesta quarta-feira (2) a descoberta de um misterioso objeto que pode ter vindo de fora do Sistema Solar. Batizado de\u00a0A11pl3Z, o corpo celeste tem entre\u00a010 e 20 quil\u00f4metros de di\u00e2metro\u00a0e chamou aten\u00e7\u00e3o pela\u00a0\u00f3rbita altamente exc\u00eantrica, o que sugere uma origem\u00a0interestelar\u00a0\u2014 ou seja, de\u00a0outra regi\u00e3o da gal\u00e1xia.<\/p>\n\n\n\n<p>Segundo Richard Moissl, chefe de defesa planet\u00e1ria da ESA,&nbsp;n\u00e3o h\u00e1 risco de colis\u00e3o com a Terra. A passagem mais pr\u00f3xima do objeto ser\u00e1 a&nbsp;50 milh\u00f5es de quil\u00f4metros, cerca de&nbsp;100 vezes a dist\u00e2ncia entre a Terra e a Lua.<\/p>\n\n\n\n<p>A descoberta de A11pl3Z rapidamente repercutiu na comunidade cient\u00edfica por conta da&nbsp;<strong>excentricidade da sua \u00f3rbita<\/strong>, medida que indica o qu\u00e3o alongado \u00e9 o caminho do corpo em rela\u00e7\u00e3o ao Sol.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>A11pl3Z tem excentricidade superior a 6<\/strong>, valor&nbsp;<strong>in\u00e9dito entre objetos j\u00e1 identificados<\/strong>&nbsp;no Sistema Solar.<\/li>\n\n\n\n<li>Para compara\u00e7\u00e3o,&nbsp;<strong>Oumuamua<\/strong>, famoso corpo interestelar descoberto em 2017, tinha excentricidade de apenas&nbsp;<strong>1,2<\/strong>.<\/li>\n\n\n\n<li>O cometa&nbsp;<strong>Borisov<\/strong>, detectado em 2019, tamb\u00e9m ficou pouco acima de&nbsp;<strong>1<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p>Com essa trajet\u00f3ria, astr\u00f4nomos acreditam que&nbsp;o objeto est\u00e1 apenas \u201cde passagem\u201d pelo Sistema Solar, vindo do espa\u00e7o profundo e&nbsp;retornando para l\u00e1 em breve. Isso o classifica como&nbsp;um dos corpos celestes mais extremos j\u00e1 registrados.<\/p>\n\n\n\n<p>Apesar da origem aparentemente distante,\u00a0um grupo de astr\u00f4nomos independentes especula que A11pl3Z poderia ter passado pr\u00f3ximo a Marte em algum ponto de sua trajet\u00f3ria. Embora ainda n\u00e3o haja evid\u00eancias formais, a possibilidade de\u00a0o objeto ter captado ou interagido com material marciano \u2014 ou at\u00e9 com formas microsc\u00f3picas de vida\u00a0\u2014 n\u00e3o foi descartada por completo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Descoberta foi feita por estudante com pseud\u00f4nimo \u201castrafoxen\u201d<\/h3>\n\n\n\n<p>A detec\u00e7\u00e3o inicial de A11pl3Z foi feita pelo\u00a0ATLAS Sky Survey, sistema de monitoramento astron\u00f4mico, e revelada ao p\u00fablico por um jovem estudante que usa o nome\u00a0\u201castrafoxen\u201d\u00a0nas redes sociais. Desde ent\u00e3o, observat\u00f3rios em diferentes partes do mundo t\u00eam reunido dados e\u00a0registros fotogr\u00e1ficos datados desde junho, para mapear com mais precis\u00e3o sua trajet\u00f3ria.<\/p>\n\n\n\n<p>A\u00a0Uni\u00e3o Astron\u00f4mica Internacional ainda precisa confirmar a classifica\u00e7\u00e3o definitiva\u00a0do objeto como corpo interestelar. At\u00e9 l\u00e1, A11pl3Z segue em estudo ativo por cientistas e astr\u00f4nomos amadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Astr\u00f4nomos da Ag\u00eancia Espacial Europeia (ESA) anunciaram nesta quarta-feira (2) a descoberta de um misterioso objeto que pode ter vindo de fora do Sistema Solar. Batizado de\u00a0A11pl3Z, o corpo celeste tem entre\u00a010 e 20 quil\u00f4metros de di\u00e2metro\u00a0e chamou aten\u00e7\u00e3o pela\u00a0\u00f3rbita altamente exc\u00eantrica, o que sugere uma origem\u00a0interestelar\u00a0\u2014 ou seja, de\u00a0outra regi\u00e3o da gal\u00e1xia. Segundo Richard [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":12051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/12037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=12037"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/12037\/revisions"}],"predecessor-version":[{"id":12052,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/12037\/revisions\/12052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/12051"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=12037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=12037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=12037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}