{"id":21831,"date":"2025-10-10T08:41:47","date_gmt":"2025-10-10T11:41:47","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=21831"},"modified":"2025-10-10T08:41:49","modified_gmt":"2025-10-10T11:41:49","slug":"revelada-a-verdadeira-assassina-de-odete-roitman","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/revelada-a-verdadeira-assassina-de-odete-roitman\/","title":{"rendered":"Revelada a verdadeira assassina de Odete Roitman"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mesmo quem n\u00e3o assiste \u00e0 novela Vale Tudo, provavelmente viu alguma postagem ou conversa na rua com teorias sobre quem matou Odete Roitman (Debora Bloch). O cap\u00edtulo com a aguardada morte da vil\u00e3 foi ao ar na \u00faltima segunda-feira (6) e temos cinco suspeitos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>C\u00e9sar (Cau\u00e3 Reymond);<\/li>\n\n\n\n<li>Maria de F\u00e1tima (Bella Campos);<\/li>\n\n\n\n<li>Heleninha (Paolla Oliveira);<\/li>\n\n\n\n<li>Celina (Malu Galli);<\/li>\n\n\n\n<li>Marco Aur\u00e9lio (Alexandre Nero).<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1200\" height=\"540\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/10\/suspeitos-morte-odete-vale-tudo.jpg\" alt=\"suspeitos morte odete vale tudo\" class=\"wp-image-21640\" srcset=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/10\/suspeitos-morte-odete-vale-tudo.jpg 1200w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/10\/suspeitos-morte-odete-vale-tudo-300x135.jpg 300w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/10\/suspeitos-morte-odete-vale-tudo-768x346.jpg 768w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/10\/suspeitos-morte-odete-vale-tudo-150x68.jpg 150w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/10\/suspeitos-morte-odete-vale-tudo-750x338.jpg 750w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/10\/suspeitos-morte-odete-vale-tudo-1140x513.jpg 1140w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Imagens: Globo<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">J\u00e1 sabemos quem matou Odete Roitman?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Alguns trechos do roteiro vazaram na imprensa e podem indicar quem deu cabo da megera. De acordo com a colunista Carla Bittencourt, do portal Leo Dias, Heleninha (Paolla Oliveira) vai at\u00e9 a delegacia confessar o crime, mas a tia Celina (Malu Galli) interv\u00e9m e diz que foi ela quem matou Odete.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heleninha, uma alcoolista em recupera\u00e7\u00e3o, estava em uma reca\u00edda no dia da morte de Odete. Ela perdeu parte da mem\u00f3ria, mas tem lapsos que a fazem acreditar que pode ter sido respons\u00e1vel pela morte da m\u00e3e. Para proteger a sobrinha, Celina fez que Heleninha estava em surto alco\u00f3lico e diz que foi ela quem matou a pr\u00f3pria irm\u00e3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m j\u00e1 sabemos que os agentes v\u00e3o encontrar as digitais das duas mulheres na arma do crime, mas eles v\u00e3o continuar em d\u00favida se Celina foi realmente a respons\u00e1vel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Que dia vamos descobrir quem matou Odete Roitman?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00f3 vamos descobrir a resposta definitiva do mist\u00e9rio no \u00faltimo cap\u00edtulo da trama, que vai ao ar na sexta-feira que vem, no dia 17 de outubro. A novela das nove ser\u00e1 substitu\u00edda por Tr\u00eas Gra\u00e7as, do autor Aguinaldo Silva e com dire\u00e7\u00e3o art\u00edstica de Luiz Henrique Rios.<\/p>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/homem-vai-parar-no-hospital-depois-de-comer-3-kg-de-bala\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/10\/balas.jpg\" data-src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/10\/balas.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>CURIOSIDADES<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Homem vai parar no hospital depois de comer 3 kg de bala<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Um brit\u00e2nico de 33 anos foi parar no hospital depois de comer 3 kg de balas de gelatina em tr\u00eas \u2026<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Leia mais<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/homem-vai-parar-no-hospital-depois-de-comer-3-kg-de-bala\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/10\/balas.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Homem vai parar no hospital depois de comer 3 kg de bala<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Leia mais<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>O mist\u00e9rio de quem matou Odete Roitman no remake de Vale Tudo tem mexido com a curiosidade dos espectadores essa semana.<\/p>\n","protected":false},"author":6,"featured_media":21385,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-21831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/21831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=21831"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/21831\/revisions"}],"predecessor-version":[{"id":21840,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/21831\/revisions\/21840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/21385"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=21831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=21831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=21831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}