{"id":22476,"date":"2025-10-16T16:59:00","date_gmt":"2025-10-16T19:59:00","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=22476"},"modified":"2025-10-16T16:35:16","modified_gmt":"2025-10-16T19:35:16","slug":"anos-mascarando-seu-nome-verdadeiro-quem-william-bonner-realmente-e","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/anos-mascarando-seu-nome-verdadeiro-quem-william-bonner-realmente-e\/","title":{"rendered":"Anos mascarando seu nome verdadeiro: quem William Bonner realmente \u00e9"},"content":{"rendered":"\n<p><strong>William Bonner <\/strong>anunciou sua despedida do &#8220;Jornal Nacional&#8221;, onde atuou por quase tr\u00eas d\u00e9cadas, sendo editor-chefe por 26 anos. Seu \u00faltimo dia no telejornal vai ser dia 3 de novembro, com C\u00e9sar Tralli assumindo como \u00e2ncora a partir de 1\u00ba de novembro.<\/p>\n\n\n\n<p>Bonner expressou o desejo de dedicar mais tempo \u00e0 fam\u00edlia e a projetos pessoais. Essa decis\u00e3o encerra um ciclo significativo para o jornalista e marca o in\u00edcio de uma nova etapa no &#8220;Globo Rep\u00f3rter&#8221;, onde Bonner se juntar\u00e1 a Sandra Annenberg em 2026.<\/p>\n\n\n\n<p>Apesar de ser conhecido como William Bonner, o verdadeiro nome do apresentador \u00e9 William <strong>Bonemer <\/strong>J\u00fanior.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Trajet\u00f3ria no jornalismo<\/h2>\n\n\n\n<p>Desde que iniciou sua participa\u00e7\u00e3o no &#8220;Jornal Nacional&#8221; em 1996, William Bonner firmou-se como uma das personalidades mais respeitadas da telinha. Ele assumiu a bancada ao lado de F\u00e1tima Bernardes, estabelecendo uma din\u00e2mica reconhecida pela qualidade e precis\u00e3o das informa\u00e7\u00f5es.<\/p>\n\n\n\n<p>Durante sua gest\u00e3o, o &#8220;JN&#8221; cobriu eventos hist\u00f3ricos, como o atentado de 11 de setembro nos Estados Unidos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Transforma\u00e7\u00f5es&nbsp;<\/h2>\n\n\n\n<p>Ao longo de sua carreira, Bonner n\u00e3o apenas reportou as not\u00edcias, mas tamb\u00e9m foi fundamental no processo de moderniza\u00e7\u00e3o do &#8220;Jornal Nacional&#8221;. Sob sua lideran\u00e7a, o telejornal incorporou inova\u00e7\u00f5es tecnol\u00f3gicas e novos padr\u00f5es editoriais para manter sua relev\u00e2ncia em um cen\u00e1rio midi\u00e1tico em constante evolu\u00e7\u00e3o.<\/p>\n\n\n\n<p>Ele influenciou a maneira como as not\u00edcias s\u00e3o apresentadas e consumidas, desempenhando um papel crucial na adapta\u00e7\u00e3o do &#8220;JN&#8221; \u00e0s mudan\u00e7as do p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Respeitado apresentador anunciou sa\u00edda do Jornal Nacional. Seu verdadeiro nome \u00e9 pouco conhecido.<\/p>\n","protected":false},"author":12,"featured_media":17943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-22476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/22476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=22476"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/22476\/revisions"}],"predecessor-version":[{"id":22482,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/22476\/revisions\/22482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/17943"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=22476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=22476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=22476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}