{"id":25185,"date":"2025-11-07T17:21:06","date_gmt":"2025-11-07T20:21:06","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=25185"},"modified":"2025-11-07T17:21:08","modified_gmt":"2025-11-07T20:21:08","slug":"apos-sucesso-na-serie-suzane-von-richthofen-abre-loja-para-vender-produtos-personalizados","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/apos-sucesso-na-serie-suzane-von-richthofen-abre-loja-para-vender-produtos-personalizados\/","title":{"rendered":"Ap\u00f3s sucesso na s\u00e9rie, Suzane von Richthofen abre loja para vender produtos personalizados"},"content":{"rendered":"\n<p>A enorme repercuss\u00e3o da s\u00e9rie Trememb\u00e9, do Prime Video, reacendeu o interesse p\u00fablico em v\u00e1rios criminosos conhecidos do nosso pa\u00eds, uma delas sendo Suzane von Richthofen, vivida por Marina Ruy Barbosa na s\u00e9rie. E parece que a pr\u00f3pria Suzane percebeu isso e decidiu aproveitar o momento para reativar a sua lojinha de personalizados no Instagram: a Su Entre Linhas, que estava desativada desde dezembro do ano passado.<\/p>\n\n\n\n<p>A loja vende chinelos personalizados, bolsas, jogos americanos e outros produtos artesanais. Nessa volta, ela apresentou novos produtos, incluindo modelos de chinelos custando entre R$ 150 e R$ 180 (sem o frete). O perfil no Instagram atualmente conta com mais de 70 mil seguidores. Suzane chegou a abrir os coment\u00e1rios das postagens, mas fechou a se\u00e7\u00e3o novamente ap\u00f3s uma s\u00e9rie de cr\u00edticas. <\/p>\n\n\n\n<p>Suzane von Richthofen foi condenada a 39 anos de pris\u00e3o em 2006 por arquitetar o assassinato dos pais em 2002, com a ajuda do ent\u00e3o namorado, Daniel Cravinhos, e do seu irm\u00e3o, Cristian. Depois de 13 anos cumprindo a pena em regime fechado, ela passou para o semiaberto em 2015 e, no in\u00edcio de 2023, passou para o regime aberto. <\/p>\n\n\n\n<p>Atualmente, ela cursa Direito e \u00e9 casada com o m\u00e9dico Felipe Zecchini Muniz e teve seu primeiro filho em janeiro do ano passado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Trememb\u00e9<\/h2>\n\n\n\n<p><em>\u201cA chegada de Suzane Von Richthofen abala a ordem em Trememb\u00e9 e inicia uma disputa com Elize Matsunaga, enquanto Jatob\u00e1, Nardoni, Roger, Daniel e Cristian Cravinhos, entre outros criminosos, desafiam o sistema, em meio a conflitos internos e externos\u201d<\/em>&nbsp;(sinopse oficial do Prime Video).<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"Trememb\u00e9 | Trailer Oficial | Prime Video\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ntEbzX0wzxQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/tremembe-criminoso-retratado-na-serie-reclama-que-o-ator-era-feio\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/11\/tremembe.jpg\" data-src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/11\/tremembe.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>TREMEMB\u00c9<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Trememb\u00e9: criminoso retratado na s\u00e9rie reclama que o ator era &quot;feio&quot;<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Um dos criminosos reais retratados na s\u00e9rie do Prime Video Trememb\u00e9 fez uma reclama\u00e7\u00e3o um tanto quanto inusitada sobre a \u2026<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Leia mais<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/tremembe-criminoso-retratado-na-serie-reclama-que-o-ator-era-feio\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/11\/tremembe.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Trememb\u00e9: criminoso retratado na s\u00e9rie reclama que o ator era &quot;feio&quot;<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Leia mais<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>A enorme repercuss\u00e3o da s\u00e9rie Trememb\u00e9, do Prime Video, reacendeu o interesse p\u00fablico em v\u00e1rios criminosos conhecidos do nosso pa\u00eds, uma delas sendo Suzane von Richthofen, vivida por Marina Ruy Barbosa na s\u00e9rie. E parece que a pr\u00f3pria Suzane percebeu isso e decidiu aproveitar o momento para reativar a sua lojinha de personalizados no Instagram: [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":25186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/25185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=25185"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/25185\/revisions"}],"predecessor-version":[{"id":25187,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/25185\/revisions\/25187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/25186"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=25185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=25185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=25185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}