{"id":25212,"date":"2025-11-09T18:02:00","date_gmt":"2025-11-09T21:02:00","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=25212"},"modified":"2025-11-07T18:47:49","modified_gmt":"2025-11-07T21:47:49","slug":"tremembe-o-que-significa-gostar-de-ver-historias-de-criminosos-segundo-especialistas","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/tremembe-o-que-significa-gostar-de-ver-historias-de-criminosos-segundo-especialistas\/","title":{"rendered":"Trememb\u00e9: o que significa gostar de ver hist\u00f3rias de criminosos, segundo especialistas"},"content":{"rendered":"\n<p>Ame ou odeie, n\u00e3o tem como negar que a s\u00e9rie Trememb\u00e9, do Prime Video, \u00e9 um sucesso. Lan\u00e7ada no dia 31 de outubro, a produ\u00e7\u00e3o se tornou o maior sucesso nacional do streaming desde a sua chegada ao Brasil, l\u00e1 em 2016, segundo o pr\u00f3prio Prime Video. A s\u00e9rie de pris\u00e3o obviamente atraiu muita aten\u00e7\u00e3o por se inspirar nas hist\u00f3rias de criminosos reais e muito conhecidos, como Suzane von Richthofen, Elize Matsunaga, Alexandre Nardoni e Anna Carolina Jatob\u00e1.<\/p>\n\n\n\n<p>Apesar de ser basicamente uma hist\u00f3ria de pris\u00e3o (\u00e0 la Orange is the new Black), a presen\u00e7a desses criminosos transformou a s\u00e9rie em mais um exemplar do fen\u00f4meno true crime. Hist\u00f3rias de crimes reais, seja relatos documentais ou ficcionalizados, t\u00eam feito muito sucesso nos \u00faltimos anos, gerando debates \u00e9ticos e at\u00e9 morais: afinal, o que explica a fascina\u00e7\u00e3o do p\u00fablico por essas hist\u00f3rias?<\/p>\n\n\n\n<p>Consultada pela Isto\u00e9, a neuropsicanalista Priscila Gasparini Fernandes, doutorada pela USP, explica que essa curiosidade sobre crimes \u00e9 um comportamento &#8220;normal e esperado&#8221;. Segundo a especialista, desde a antiguidade, quando t\u00ednhamos espet\u00e1culos de execu\u00e7\u00e3o de criminosos em pra\u00e7a p\u00fablica, o ser humano sente curiosidade em rela\u00e7\u00e3o a crimes e viol\u00eancia.<\/p>\n\n\n\n<p><em>\u201dA curiosidade \u00e9 a chave em rela\u00e7\u00e3o ao fasc\u00ednio da viol\u00eancia. As pessoas tem o interesse e, por curiosidade, querem acompanhar o caso, assistir e avaliar cada detalhe, mas de uma maneira segura, onde n\u00e3o correm perigo, em um ambiente controlado\u201d<\/em>, explica a psicanalista.<\/p>\n\n\n\n<p>Ela ainda completa que, de certa forma, a pessoa que est\u00e1 consumindo aquele conte\u00fado tem um certo al\u00edvio: pelo menos aquele crime horroroso aconteceu com outra pessoa, n\u00e3o com ela ou com algu\u00e9m que ela ama.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Trememb\u00e9<\/h2>\n\n\n\n<p><em>\u201cA chegada de Suzane Von Richthofen abala a ordem em Trememb\u00e9 e inicia uma disputa com Elize Matsunaga, enquanto Jatob\u00e1, Nardoni, Roger, Daniel e Cristian Cravinhos, entre outros criminosos, desafiam o sistema, em meio a conflitos internos e externos\u201d<\/em>&nbsp;(sinopse oficial do Prime Video).<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"Trememb\u00e9 | Trailer Oficial | Prime Video\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ntEbzX0wzxQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/tremembe-criminoso-retratado-na-serie-reclama-que-o-ator-era-feio\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/11\/tremembe.jpg\" data-src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/11\/tremembe.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>TREMEMB\u00c9<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Trememb\u00e9: criminoso retratado na s\u00e9rie reclama que o ator era &quot;feio&quot;<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Um dos criminosos reais retratados na s\u00e9rie do Prime Video Trememb\u00e9 fez uma reclama\u00e7\u00e3o um tanto quanto inusitada sobre a \u2026<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Leia mais<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/tremembe-criminoso-retratado-na-serie-reclama-que-o-ator-era-feio\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/11\/tremembe.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Trememb\u00e9: criminoso retratado na s\u00e9rie reclama que o ator era &quot;feio&quot;<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Leia mais<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ame ou odeie, n\u00e3o tem como negar que a s\u00e9rie Trememb\u00e9, do Prime Video, \u00e9 um sucesso. Lan\u00e7ada no dia 31 de outubro, a produ\u00e7\u00e3o se tornou o maior sucesso nacional do streaming desde a sua chegada ao Brasil, l\u00e1 em 2016, segundo o pr\u00f3prio Prime Video. A s\u00e9rie de pris\u00e3o obviamente atraiu muita aten\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":25213,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/25212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=25212"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/25212\/revisions"}],"predecessor-version":[{"id":25214,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/25212\/revisions\/25214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/25213"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=25212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=25212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=25212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}