{"id":30778,"date":"2026-01-05T10:01:15","date_gmt":"2026-01-05T13:01:15","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=30778"},"modified":"2026-01-05T10:01:18","modified_gmt":"2026-01-05T13:01:18","slug":"novo-comprimido-desenvolvido-por-cientistas-queima-gordura-mesmo-sem-exercicios-fisicos","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/novo-comprimido-desenvolvido-por-cientistas-queima-gordura-mesmo-sem-exercicios-fisicos\/","title":{"rendered":"Novo comprimido desenvolvido por cientistas queima gordura mesmo sem exerc\u00edcios f\u00edsicos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Um novo medicamento em forma de comprimido foi capaz de estimular a queima de gordura mesmo em repouso, sem provocar perda de massa muscular, segundo testes em animais e um estudo cl\u00ednico inicial com humanos. A descoberta, publicada na revista cient\u00edfica <em>Cell<\/em>, pode abrir caminho para uma nova abordagem no tratamento da obesidade e do diabetes tipo 2, ao melhorar o controle da glicose e aumentar o gasto energ\u00e9tico sem os efeitos colaterais mais comuns das terapias atuais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao contr\u00e1rio dos medicamentos \u00e0 base de GLP-1 \u2014 como Ozempic e similares \u2014, que atuam no controle do apetite por meio da comunica\u00e7\u00e3o entre intestino e c\u00e9rebro e s\u00e3o aplicados por inje\u00e7\u00e3o, o novo f\u00e1rmaco age diretamente no metabolismo do m\u00fasculo esquel\u00e9tico. Segundo os pesquisadores, essa diferen\u00e7a explica por que a subst\u00e2ncia n\u00e3o causa efeitos frequentes associados aos GLP-1, como perda de apetite excessiva, redu\u00e7\u00e3o de massa muscular e problemas gastrointestinais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em<a href=\"https:\/\/news.ki.se\/new-drug-for-diabetes-and-obesity-shows-promising-results\" target=\"_blank\" rel=\"noopener\"> estudos pr\u00e9-cl\u00ednicos<\/a>, o composto melhorou a composi\u00e7\u00e3o corporal e o controle da glicemia sem sobrecarregar o cora\u00e7\u00e3o. Esses resultados se repetiram em um estudo cl\u00ednico de fase I, que envolveu 48 volunt\u00e1rios saud\u00e1veis e 25 pessoas com diabetes tipo 2, demonstrando boa toler\u00e2ncia ao tratamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNossos resultados apontam para um futuro em que podemos melhorar a sa\u00fade metab\u00f3lica sem perder massa muscular. Os m\u00fasculos s\u00e3o importantes tanto no diabetes tipo 2 quanto na obesidade, e a massa muscular tamb\u00e9m est\u00e1 diretamente correlacionada \u00e0 expectativa de vida\u201d, afirmou Tore Bengtsson, professor do Departamento de Bioci\u00eancias Moleculares do Instituto Wenner-Gren, da Universidade de Estocolmo, e um dos autores do estudo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"785\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-13-1200x785.png\" alt=\"\" class=\"wp-image-30781\" srcset=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-13-1200x785.png 1200w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-13-300x196.png 300w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-13-768x502.png 768w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-13-150x98.png 150w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-13-750x491.png 750w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-13-1140x746.png 1140w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-13.png 1500w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Agonismo enviesado evita efeitos no cora\u00e7\u00e3o<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A subst\u00e2ncia \u00e9 baseada em um novo tipo de agonista beta-2 adren\u00e9rgico, desenvolvido em laborat\u00f3rio para ativar apenas vias espec\u00edficas de sinaliza\u00e7\u00e3o celular. Diferentemente de medicamentos mais antigos, que estimulam amplamente o sistema adren\u00e9rgico \u2014 associado \u00e0 resposta ao estresse \u2014, o novo composto utiliza uma estrat\u00e9gia chamada de <strong>agonismo enviesado<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na pr\u00e1tica, o medicamento \u201cliga\u201d apenas a rota celular mediada pela prote\u00edna GRK2, respons\u00e1vel por aumentar a capta\u00e7\u00e3o de glicose pelos m\u00fasculos e elevar o gasto energ\u00e9tico, inclusive em repouso. Ao mesmo tempo, evita ativar caminhos que aceleram excessivamente os batimentos card\u00edacos, reduzindo o risco de taquicardia e danos cardiovasculares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com isso, o f\u00e1rmaco consegue aumentar a queima de gordura, melhorar o controle do a\u00e7\u00facar no sangue e preservar a massa muscular \u2014 um dos principais desafios nos tratamentos atuais contra a obesidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Uso isolado ou combinado com GLP-1<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Outro ponto destacado pelos cientistas \u00e9 que o novo medicamento pode ser usado tanto de forma isolada quanto em combina\u00e7\u00e3o com drogas \u00e0 base de GLP-1, j\u00e1 que os mecanismos de a\u00e7\u00e3o s\u00e3o distintos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsse medicamento representa um tipo completamente novo de tratamento e tem potencial para ser de grande import\u00e2ncia para pacientes com diabetes tipo 2 e obesidade. Nossa subst\u00e2ncia parece promover uma perda de peso saud\u00e1vel e, al\u00e9m disso, os pacientes n\u00e3o precisam tomar inje\u00e7\u00f5es\u201d, disse Shane C. Wright, professor assistente do Departamento de Fisiologia e Farmacologia do Instituto Karolinska e coautor do estudo. Segundo ele, a possibilidade de uso combinado amplia o valor terap\u00eautico da descoberta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pr\u00f3ximos passos e conflitos de interesse<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O pr\u00f3ximo est\u00e1gio da pesquisa ser\u00e1 um estudo cl\u00ednico de fase II, planejado pela empresa sueca Atrogi AB, respons\u00e1vel pelo desenvolvimento do medicamento. O objetivo \u00e9 avaliar se os benef\u00edcios observados em laborat\u00f3rio e na fase inicial tamb\u00e9m se confirmam em pessoas com obesidade ou diabetes tipo 2 em maior escala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O trabalho \u00e9 fruto de uma colabora\u00e7\u00e3o internacional envolvendo pesquisadores da Universidade de Estocolmo, Instituto Karolinska, Universidade de Uppsala, Universidade de Copenhague, al\u00e9m de institui\u00e7\u00f5es da Austr\u00e1lia. O financiamento veio de entidades como o Conselho Sueco de Pesquisa e a Funda\u00e7\u00e3o Novo Nordisk.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os autores informam que alguns pesquisadores t\u00eam v\u00ednculos com a Atrogi AB. Tore Bengtsson \u00e9 fundador e diretor cient\u00edfico da empresa e, junto com um coautor, solicitou patentes relacionadas \u00e0s subst\u00e2ncias estudadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um novo medicamento em forma de comprimido foi capaz de estimular a queima de gordura mesmo em repouso, sem provocar perda de massa muscular, segundo testes em animais e um estudo cl\u00ednico inicial com humanos. A descoberta, publicada na revista cient\u00edfica Cell, pode abrir caminho para uma nova abordagem no tratamento da obesidade e do [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":9702,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/30778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=30778"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/30778\/revisions"}],"predecessor-version":[{"id":30782,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/30778\/revisions\/30782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/9702"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=30778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=30778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=30778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}