{"id":31111,"date":"2026-01-11T21:06:00","date_gmt":"2026-01-12T00:06:00","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=31111"},"modified":"2026-01-12T18:19:05","modified_gmt":"2026-01-12T21:19:05","slug":"maior-jogador-do-nbb-faz-oscar-schimidt-parecer-baixinho-e-vira-destaque-do-bauru","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/maior-jogador-do-nbb-faz-oscar-schimidt-parecer-baixinho-e-vira-destaque-do-bauru\/","title":{"rendered":"Maior jogador do NBB faz Oscar Schimidt parecer baixinho e vira destaque do Bauru"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Com 2,13 metros de altura \u2014 oito cent\u00edmetros a mais que Oscar Schmidt, dono de 2,05 m e \u00edcone hist\u00f3rico do basquete brasileiro \u2014 o piv\u00f4 <strong>Andr\u00e9z\u00e3o<\/strong>, de apenas 22 anos, vem chamando aten\u00e7\u00e3o no <strong>NBB CAIXA 2025\/26<\/strong>. Maior jogador em atividade na liga, ele se transformou no principal destaque do <strong>Bauru Basket<\/strong>, liderando estat\u00edsticas e impondo dom\u00ednio f\u00edsico e t\u00e9cnico no garraf\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mesmo jovem, Andr\u00e9z\u00e3o j\u00e1 disputa sua <strong>sexta edi\u00e7\u00e3o do NBB<\/strong> e vive o melhor momento da carreira. Em 19 partidas, o piv\u00f4 soma <strong>336 pontos<\/strong>, com m\u00e9dia de <strong>17,68 por jogo<\/strong>, al\u00e9m de liderar a competi\u00e7\u00e3o em <strong>rebotes (10,6 por partida)<\/strong>, efici\u00eancia, arremessos de dois pontos convertidos e n\u00famero de <strong>duplos-duplos<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O desempenho consistente fez do jogador o <strong>grande destaque da segunda semana do NBB CAIXA 2025\/26<\/strong>. No per\u00edodo, ele registrou m\u00e9dias de <strong>20,5 pontos e 14 rebotes<\/strong>, alcan\u00e7ando <strong>31,5 de efici\u00eancia<\/strong>, n\u00fameros decisivos para a rea\u00e7\u00e3o do Bauru Basket ap\u00f3s um in\u00edcio de temporada marcado por tr\u00eas derrotas consecutivas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-43.png\" alt=\"\" class=\"wp-image-31113\" srcset=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-43.png 1200w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-43-300x200.png 300w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-43-768x512.png 768w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-43-150x100.png 150w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-43-750x500.png 750w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-43-1140x760.png 1140w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Andrez\u00e3o (Reprodu\u00e7\u00e3o\/Andrews Clayton)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>For\u00e7a, t\u00e9cnica e maturidade precoce<\/strong><\/h2>\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/neymar-surpreende-todo-mundo-e-vai-vestir-a-camisa-do-palmeiras-em-2026\/?utm_source=lazy\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/05\/GettyImages-1446977379.jpg-1140x570.jpg\" data-src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/05\/GettyImages-1446977379.jpg-1140x570.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>Futebol Brasil<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Choque no futebol \u26bd<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Neymar pode vestir a camisa do Palmeiras em 2026<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Veja os detalhes<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/neymar-surpreende-todo-mundo-e-vai-vestir-a-camisa-do-palmeiras-em-2026\/?utm_source=lazy\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/05\/GettyImages-1446977379.jpg-1140x570.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Choque no futebol \u26bd<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Veja os detalhes<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Sob o comando do t\u00e9cnico <strong>Paulo Ja\u00fa<\/strong>, Andr\u00e9z\u00e3o se consolidou como a principal refer\u00eancia ofensiva e defensiva da equipe. A combina\u00e7\u00e3o de <strong>for\u00e7a f\u00edsica, leitura de jogo e intelig\u00eancia t\u00e1tica<\/strong> faz com que o piv\u00f4 seja constantemente acionado nos momentos decisivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na m\u00e9dia geral da temporada, os n\u00fameros seguem expressivos: <strong>18,3 pontos, 11,8 rebotes e 24 de efici\u00eancia<\/strong> por partida. O rendimento refor\u00e7a a expectativa de que o Bauru volte a brigar na parte de cima da tabela, repetindo o desempenho das \u00faltimas duas edi\u00e7\u00f5es do campeonato, quando o clube chegou \u00e0 <strong>semifinal do NBB<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Altura que impressiona, jogo que convence<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A compara\u00e7\u00e3o com Oscar Schmidt, um dos maiores jogadores da hist\u00f3ria do basquete mundial, chama aten\u00e7\u00e3o n\u00e3o apenas pela estatura. Se Oscar marcou \u00e9poca pelo arremesso preciso e protagonismo ofensivo, Andr\u00e9z\u00e3o constr\u00f3i sua trajet\u00f3ria com <strong>dom\u00ednio no jogo interno e regularidade estat\u00edstica<\/strong>, tornando-se pe\u00e7a-chave em ambos os lados da quadra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com 2,13 metros de altura \u2014 oito cent\u00edmetros a mais que Oscar Schmidt, dono de 2,05 m e \u00edcone hist\u00f3rico do basquete brasileiro \u2014 o piv\u00f4 Andr\u00e9z\u00e3o, de apenas 22 anos, vem chamando aten\u00e7\u00e3o no NBB CAIXA 2025\/26. Maior jogador em atividade na liga, ele se transformou no principal destaque do Bauru Basket, liderando estat\u00edsticas [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":31112,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/31111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=31111"}],"version-history":[{"count":2,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/31111\/revisions"}],"predecessor-version":[{"id":31733,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/31111\/revisions\/31733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/31112"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=31111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=31111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=31111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}