{"id":31274,"date":"2026-01-11T21:28:27","date_gmt":"2026-01-12T00:28:27","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=31274"},"modified":"2026-01-09T11:01:38","modified_gmt":"2026-01-09T14:01:38","slug":"supermercados-excluem-sacolas-plasticas-e-clientes-tem-que-levar-suas-proprias-compras-em-outro-lugar-neste-pais","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/supermercados-excluem-sacolas-plasticas-e-clientes-tem-que-levar-suas-proprias-compras-em-outro-lugar-neste-pais\/","title":{"rendered":"Supermercados excluem sacolas pl\u00e1sticas e clientes t\u00eam que levar suas pr\u00f3prias compras em outro lugar neste pa\u00eds"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Os supermercados da <strong>Calif\u00f3rnia<\/strong>, nos <strong>Estados Unidos<\/strong>, come\u00e7aram 2026 com uma mudan\u00e7a que afeta diretamente a rotina dos consumidores: desde <strong>1\u00ba de janeiro<\/strong>, est\u00e1 <strong>totalmente proibida a distribui\u00e7\u00e3o de sacolas pl\u00e1sticas<\/strong> em estabelecimentos comerciais. A nova regra obriga os clientes a levarem suas pr\u00f3prias sacolas ou utilizarem alternativas como <strong>sacos de papel reciclado<\/strong>, dispon\u00edveis para venda no caixa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A medida faz parte da <strong>Senate Bill 1053 (SB 1053)<\/strong>, legisla\u00e7\u00e3o estadual que fecha a \u00faltima brecha existente na pol\u00edtica ambiental adotada pelo estado desde 2014.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 ent\u00e3o, a Calif\u00f3rnia j\u00e1 proibia sacolas pl\u00e1sticas finas, mas permitia o uso e a venda das vers\u00f5es mais espessas, classificadas como reutiliz\u00e1veis. O efeito, no entanto, foi o oposto do esperado. Dados da ag\u00eancia ambiental estadual <strong>CalRecycle<\/strong> mostram que o descarte de sacolas pl\u00e1sticas <strong>aumentou 47% entre 2014 e 2022<\/strong>, impulsionado justamente por esses modelos mais grossos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a nova lei, <strong>nem mesmo essas sacolas est\u00e3o mais autorizadas<\/strong>. Apenas sacolas de papel e reutiliz\u00e1veis de outros materiais podem ser oferecidas aos consumidores, seguindo regras espec\u00edficas de resist\u00eancia e sustentabilidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Objetivo \u00e9 reduzir o lixo pl\u00e1stico<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A SB 1053 foi aprovada e sancionada em 2024 pelo governador <strong>Gavin Newsom<\/strong>, mas teve a aplica\u00e7\u00e3o adiada por um ano para que os comerciantes pudessem esgotar seus estoques. Segundo <strong>Andrew LaMar<\/strong>, representante da senadora <strong>Catherine Blakespear<\/strong>, autora do projeto, a inten\u00e7\u00e3o foi garantir uma transi\u00e7\u00e3o organizada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em nota oficial, Blakespear afirmou que a nova legisla\u00e7\u00e3o conclui o objetivo original da lei ambiental do estado.<br>\u201cOs californianos j\u00e1 est\u00e3o prontos para fazer compras sem sacolas pl\u00e1sticas h\u00e1 muito tempo. A proibi\u00e7\u00e3o vai eliminar milh\u00f5es de sacolas do fluxo de lixo e ajudar a proteger melhor o meio ambiente\u201d, disse a senadora.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Apoio ambiental e cr\u00edticas econ\u00f4micas<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Organiza\u00e7\u00f5es ambientais celebraram a mudan\u00e7a. Para <strong>Emily Parker<\/strong>, cientista marinha s\u00eanior da ONG Heal The Bay, o impacto ser\u00e1 significativo.<br>\u201cO que mais nos anima \u00e9 saber que as sacolas pl\u00e1sticas de supermercados finalmente ser\u00e3o eliminadas por completo. A melhor forma de combater a polui\u00e7\u00e3o \u00e9 migrar para op\u00e7\u00f5es reutiliz\u00e1veis\u201d, afirmou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por outro lado, a medida enfrenta cr\u00edticas de setores econ\u00f4micos. O economista <strong>Wayne Winegarden<\/strong>, do <strong>Pacific Research Institute<\/strong>, avalia que a proibi\u00e7\u00e3o \u00e9 excessiva.<br>\u201cExistem meios mais eficazes de reciclagem e descarte adequado. Essa \u00e9 uma pol\u00edtica desnecess\u00e1ria e restritiva, que afeta a qualidade de vida na Calif\u00f3rnia\u201d, declarou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a <strong>Ag\u00eancia de Prote\u00e7\u00e3o Ambiental dos EUA (EPA)<\/strong>, o pl\u00e1stico pode levar de <strong>100 a 1.000 anos para se decompor<\/strong>, dependendo das condi\u00e7\u00f5es ambientais. Estudos cient\u00edficos indicam ainda que o material <strong>n\u00e3o \u00e9 biodegrad\u00e1vel<\/strong> e que sua incinera\u00e7\u00e3o libera subst\u00e2ncias t\u00f3xicas no ar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os supermercados da Calif\u00f3rnia, nos Estados Unidos, come\u00e7aram 2026 com uma mudan\u00e7a que afeta diretamente a rotina dos consumidores: desde 1\u00ba de janeiro, est\u00e1 totalmente proibida a distribui\u00e7\u00e3o de sacolas pl\u00e1sticas em estabelecimentos comerciais. A nova regra obriga os clientes a levarem suas pr\u00f3prias sacolas ou utilizarem alternativas como sacos de papel reciclado, dispon\u00edveis para [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31274","post","type-post","status-publish","format-standard","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/31274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=31274"}],"version-history":[{"count":2,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/31274\/revisions"}],"predecessor-version":[{"id":31489,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/31274\/revisions\/31489"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=31274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=31274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=31274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}