{"id":31781,"date":"2026-01-12T22:23:17","date_gmt":"2026-01-13T01:23:17","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=31781"},"modified":"2026-01-12T22:23:19","modified_gmt":"2026-01-13T01:23:19","slug":"iceberg-do-tamanho-do-rio-de-janeiro-pode-explodir-a-qualquer-momento-e-preocupa-a-nasa","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/iceberg-do-tamanho-do-rio-de-janeiro-pode-explodir-a-qualquer-momento-e-preocupa-a-nasa\/","title":{"rendered":"Iceberg do tamanho do Rio de Janeiro pode explodir a qualquer momento e preocupa a NASA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Imagens divulgadas pela Nasa na \u00faltima quinta-feira (8) acenderam um alerta entre cientistas: o iceberg A-23A, considerado o maior do mundo, apresenta sinais claros de colapso iminente. Atualmente com \u00e1rea equivalente \u00e0 cidade do Rio de Janeiro, a gigantesca massa de gelo flutua no Oceano Atl\u00e2ntico Sul e pode se fragmentar a qualquer momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O A-23A se desprendeu da plataforma de gelo Filchner, na Ant\u00e1rtida, em 1986, e vem sendo monitorado h\u00e1 quase quatro d\u00e9cadas. Na \u00e9poca, o iceberg tinha cerca de 4 mil km\u00b2 \u2014 mais que o dobro da \u00e1rea da cidade de S\u00e3o Paulo e pr\u00f3ximo \u00e0 extens\u00e3o do Distrito Federal. Desde ent\u00e3o, perdeu grande parte de sua massa e hoje mede aproximadamente 1.181 km\u00b2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Nasa, imagens captadas pelo sat\u00e9lite Terra em 26 de dezembro mostram a superf\u00edcie do iceberg intensamente encharcada, coberta por grandes po\u00e7as de \u00e1gua azul formadas pelo derretimento do gelo durante o ver\u00e3o do hemisf\u00e9rio sul. No dia seguinte, astronautas da Esta\u00e7\u00e3o Espacial Internacional registraram imagens ainda mais pr\u00f3ximas, evidenciando que essas po\u00e7as cresceram rapidamente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"970\" height=\"647\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-119.png\" alt=\"\" class=\"wp-image-31782\" srcset=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-119.png 970w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-119-300x200.png 300w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-119-768x512.png 768w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-119-150x100.png 150w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/image-119-750x500.png 750w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/><figcaption class=\"wp-element-caption\">Iceberg A23-A (Reprodu\u00e7\u00e3o\/NASA Earth Observatory image by Michala Garrison)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sinais de colapso acelerado<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo especialistas da Nasa, essas chamadas <em>meltwater ponds<\/em> \u2014 po\u00e7as de \u00e1gua de degelo \u2014 s\u00e3o um dos principais sinais de que um iceberg est\u00e1 perto de se romper. O peso da \u00e1gua acumulada infiltra-se em fraturas naturais do gelo, funcionando como uma cunha que for\u00e7a a abertura das rachaduras, podendo provocar uma fragmenta\u00e7\u00e3o repentina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO ac\u00famulo de \u00e1gua l\u00edquida na superf\u00edcie pode literalmente partir o iceberg em peda\u00e7os\u201d, explicam cientistas do Earth Observatory, da Nasa, ao analisar o fen\u00f4meno observado no A-23A. O entorno do iceberg tamb\u00e9m apresenta um \u201chalo\u201d de gelo fraturado, outro ind\u00edcio de instabilidade estrutural.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Impactos no oceano e no clima<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Embora o desprendimento e o derretimento de icebergs sejam processos naturais, o tamanho e a longevidade do A-23A tornam seu colapso especialmente relevante. Quando uma massa dessa propor\u00e7\u00e3o derrete, grandes volumes de \u00e1gua doce e fria s\u00e3o liberados no oceano, alterando a circula\u00e7\u00e3o local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esse processo pode favorecer a ressurg\u00eancia de \u00e1guas profundas ricas em nutrientes, estimulando o crescimento do fitopl\u00e2ncton \u2014 base da cadeia alimentar marinha. Ao mesmo tempo, os cientistas alertam que o aquecimento global tem acelerado o derretimento dessas estruturas, tornando eventos como este mais frequentes e imprevis\u00edveis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagens divulgadas pela Nasa na \u00faltima quinta-feira (8) acenderam um alerta entre cientistas: o iceberg A-23A, considerado o maior do mundo, apresenta sinais claros de colapso iminente. Atualmente com \u00e1rea equivalente \u00e0 cidade do Rio de Janeiro, a gigantesca massa de gelo flutua no Oceano Atl\u00e2ntico Sul e pode se fragmentar a qualquer momento. O [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":31783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/31781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=31781"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/31781\/revisions"}],"predecessor-version":[{"id":31784,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/31781\/revisions\/31784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/31783"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=31781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=31781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=31781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}