{"id":32014,"date":"2026-01-14T17:23:26","date_gmt":"2026-01-14T20:23:26","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=32014"},"modified":"2026-01-14T18:24:32","modified_gmt":"2026-01-14T21:24:32","slug":"filho-de-beckham-mora-em-mansao-de-quase-r-80-milhoes-e-nao-precisou-de-1-centavo-do-pai","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/filho-de-beckham-mora-em-mansao-de-quase-r-80-milhoes-e-nao-precisou-de-1-centavo-do-pai\/","title":{"rendered":"Filho de Beckham mora em mans\u00e3o de quase R$ 80 milh\u00f5es e n\u00e3o precisou de 1 centavo do pai"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">N\u00e3o \u00e9 nenhuma surpresa saber que o Brooklyn Beckham, o filho do ex-jogador David Beckham e eterna Spice Girl Victoria Beckham, mora em uma mans\u00e3o avaliada em US$ 14,1 milh\u00f5es, equivalente a cerca de R$ 76,11 milh\u00f5es. A surpresa \u00e9 saber que os pais de Brooklyn, atualmente com seus 26 anos, n\u00e3o colocaram nem um centavo na casa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na verdade, a maior parte do valor da casa foi pago pela esposa do ex-fot\u00f3grafo, a atriz Nicola Peltz (Transformers 4), de 31 anos. De acordo com o tabloide brit\u00e2nico The Sun, a maior parte do aporte financeiro para a compra do im\u00f3vel em Los Angeles, nos EUA, veio do fundo fiduci\u00e1rio da atriz. Vale destacar que ela \u00e9 filha do investidor Nelson Peltz, que tem um patrim\u00f4nio estimado em US$ 1,6 bilh\u00e3o. Segundo fontes do The Sun, o casal usou economias conjuntas, mas o apoio da fam\u00edlia da atriz foi essencial para a transa\u00e7\u00e3o ser concretizada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O im\u00f3vel conta com cinco quartos, seis banheiros, piscina de borda infinita, uma academia e um cinema em casa privados. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/casa-brooklyn-beckham-1200x675.jpg\" alt=\"casa brooklyn beckham\" class=\"wp-image-32023\" srcset=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/casa-brooklyn-beckham-1200x675.jpg 1200w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/casa-brooklyn-beckham-300x169.jpg 300w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/casa-brooklyn-beckham-768x432.jpg 768w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/casa-brooklyn-beckham-1536x864.jpg 1536w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/casa-brooklyn-beckham-150x84.jpg 150w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/casa-brooklyn-beckham-750x422.jpg 750w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/casa-brooklyn-beckham-1140x641.jpg 1140w, https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/casa-brooklyn-beckham.jpg 1920w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><figcaption class=\"wp-element-caption\">Imagem: reprodu\u00e7\u00e3o\/Compass<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Brooklyn Beckham brigou com os pais?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">As tens\u00f5es entre Brooklyn e os pais come\u00e7aram quando ele anunciou o noivado com Nicola. O casamento em 2022 com uma cerim\u00f4nia luxuosa na Fl\u00f3rida, nos EUA. Era esperado que a atriz se casasse com um modelito desenhado pela sogra, mas isso n\u00e3o aconteceu. Em entrevista, Nicola disse que foi porque o vestido n\u00e3o ficaria pronto a tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tudo se complicou com uma suposta briga entre Brooklyn e seu irm\u00e3o Romeo por causa da namorada de Romeo, Kim Turnbull, que teria namorado o outro irm\u00e3o anos antes, algo negado publicamente por outro irm\u00e3o Beckham. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre aus\u00eancias em festas, 2026 come\u00e7ou com Brooklyn enviando uma notifica\u00e7\u00e3o extrajudicial exigindo que eles se comunicassem apenas por meio de advogados, de acordo com ve\u00edculos da m\u00eddia. <em>&#8220;Ele sentia que seus pais continuavam ignorando seus desejos e o repreendiam constantemente em vez de se comunicarem com ele em particular&#8221;<\/em>, afirmou uma fonte pr\u00f3xima ao jovem ao The Sun. <\/p>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/veja-quanto-tempo-de-prancha-abdominal-o-corpo-precisa-de-acordo-com-cada-faixa-etaria\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/prancha-abdominal.jpg\" data-src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/prancha-abdominal.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>EXERC\u00cdCIO<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Veja quanto tempo de prancha abdominal o corpo precisa, de acordo com cada faixa et\u00e1ria<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Um minuto costuma passar r\u00e1pido\u2026 exceto quando voc\u00ea est\u00e1 fazendo a prancha abdominal. Descubra o tempo adequado para o exerc\u00edcio.<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Leia mais<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/veja-quanto-tempo-de-prancha-abdominal-o-corpo-precisa-de-acordo-com-cada-faixa-etaria\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/01\/prancha-abdominal.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Veja quanto tempo de prancha abdominal o corpo precisa, de acordo com cada faixa et\u00e1ria<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Leia mais<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o \u00e9 nenhuma surpresa saber que o Brooklyn Beckham, o filho do ex-jogador David Beckham e eterna Spice Girl Victoria Beckham, mora em uma mans\u00e3o avaliada em US$ 14,1 milh\u00f5es, equivalente a cerca de R$ 76,11 milh\u00f5es. A surpresa \u00e9 saber que os pais de Brooklyn, atualmente com seus 26 anos, n\u00e3o colocaram nem um [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":32017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/32014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=32014"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/32014\/revisions"}],"predecessor-version":[{"id":32028,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/32014\/revisions\/32028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/32017"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=32014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=32014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=32014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}