{"id":32075,"date":"2026-01-14T20:59:00","date_gmt":"2026-01-14T23:59:00","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=32075"},"modified":"2026-01-14T23:40:23","modified_gmt":"2026-01-15T02:40:23","slug":"brasileiros-desempregados-vao-receber-auxilio-de-ate-r-r-2-51865","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/brasileiros-desempregados-vao-receber-auxilio-de-ate-r-r-2-51865\/","title":{"rendered":"Brasileiros desempregados v\u00e3o receber aux\u00edlio de at\u00e9 R$ 2.518,65"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Os trabalhadores dispensados <strong>sem justa causa <\/strong>t\u00eam uma novidade em 2026: o reajuste no <strong>seguro-desemprego.<\/strong> Este aumento, v\u00e1lido a partir deste m\u00eas de janeiro, reflete a atualiza\u00e7\u00e3o da tabela de valores que acompanha a varia\u00e7\u00e3o de 3,9% do \u00cdndice Nacional de Pre\u00e7os ao Consumidor (INPC) de 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A mudan\u00e7a, divulgada pelo Minist\u00e9rio do Trabalho e Emprego, \u00e9 aplicada em todo o Brasil com efeito imediato, beneficiando quem j\u00e1 recebe e quem ainda vai solicitar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com o reajuste, o teto do seguro-desemprego aumentou de R$ 2.424,11 para <strong>R$ 2.518,65. <\/strong>O valor m\u00ednimo subiu de R$ 1.518 para R$ 1.621. Essas altera\u00e7\u00f5es buscam ajustar a capacidade de compra dos benefici\u00e1rios, mantendo o prop\u00f3sito inicial do aux\u00edlio: abrir uma janela de suporte tempor\u00e1rio aos desempregados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como calcular o novo benef\u00edcio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O c\u00e1lculo do seguro-desemprego baseia-se na m\u00e9dia das tr\u00eas \u00faltimas remunera\u00e7\u00f5es do trabalhador. As novas regras aplicadas a partir do reajuste de 2026 s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sal\u00e1rio m\u00e9dio at\u00e9 R$ 2.222,17:<\/strong> O benefici\u00e1rio recebe 80% da m\u00e9dia salarial ou o valor do sal\u00e1rio m\u00ednimo, prevalecendo o maior valor.<\/li>\n\n\n\n<li><strong>Sal\u00e1rio m\u00e9dio de R$ 2.222,18 a R$ 3.703,99: <\/strong>Composto por 50% sobre o que exceder R$ 2.222,17, acrescido de R$ 1.777,74.<\/li>\n\n\n\n<li><strong>Sal\u00e1rio m\u00e9dio acima de R$ 3.703,99:<\/strong> Parcela permanece fixa em R$ 2.518,65.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Essas faixas salariais visam assegurar que o aux\u00edlio efetivamente auxilie no sustento daqueles que perderam seus empregos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Crit\u00e9rios de elegibilidade<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para solicitar o seguro-desemprego, \u00e9 crucial que o trabalhador tenha sido demitido sem justa causa e se encontre desempregado no momento do pedido. \u00c9 necess\u00e1rio n\u00e3o ter renda suficiente para manter a fam\u00edlia e n\u00e3o receber outro benef\u00edcio cont\u00ednuo, exceto pens\u00e3o por morte ou aux\u00edlio-acidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A solicita\u00e7\u00e3o deve ser formalizada pelo Portal Emprega Brasil, entre o 7\u00ba e o 120\u00ba dia ap\u00f3s a demiss\u00e3o para trabalhadores formais, ou entre o 7\u00ba e o 90\u00ba dia para empregados dom\u00e9sticos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mudan\u00e7a, divulgada pelo Minist\u00e9rio do Trabalho e Emprego, \u00e9 aplicada em todo o Brasil.<\/p>\n","protected":false},"author":12,"featured_media":10089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/32075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=32075"}],"version-history":[{"count":2,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/32075\/revisions"}],"predecessor-version":[{"id":32094,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/32075\/revisions\/32094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/10089"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=32075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=32075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=32075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}