{"id":3442,"date":"2025-03-06T14:35:41","date_gmt":"2025-03-06T17:35:41","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=3442"},"modified":"2025-03-06T14:35:44","modified_gmt":"2025-03-06T17:35:44","slug":"revelado-quem-foi-o-ator-mais-bem-pago-de-2024","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/revelado-quem-foi-o-ator-mais-bem-pago-de-2024\/","title":{"rendered":"Revelado quem foi o ator mais bem pago de 2024"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A revista Forbes revelou um relat\u00f3rio que exp\u00f4s quais foram os atores mais bem pagos de 2024 em Hollywood e quem liderou o ranking foi <strong>Dwayne Johnson<\/strong>, apesar do faturamento de um dos filmes que estrelou, n\u00e3o ter alcan\u00e7ado os valores esperados. No ano passado, o ator que tamb\u00e9m \u00e9 conhecido pelo apelido The Rock, esteve presente em \u201cOpera\u00e7\u00e3o Natal\u201d e retornou para \u201cMoana 2\u201d, como um dos principais dubladores da anima\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em \u201cOpera\u00e7\u00e3o Natal\u201d, o contrato de Johnson chamou bastante a aten\u00e7\u00e3o, mesmo atuando ao lado de Chris Evans, Lucy Liu, JK Simmons, Kiernan Shipka, entre outros. De acordo com a Forbes, o astro teve direito aos honor\u00e1rios iniciais para atuar e produzir, recebendo cerca de US$ 50 milh\u00f5es, o que se acredita ser o maior total de honor\u00e1rios mais compra da hist\u00f3ria para um \u00fanico filme.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, o filme n\u00e3o teve uma recep\u00e7\u00e3o positiva nos cinemas e arrecadou apenas US$ 186 milh\u00f5es no mundo todo, contra um or\u00e7amento estimado de US$ 250 milh\u00f5es. Apesar disso, quando estreou no Amazon Prime Video um m\u00eas depois, \u201cOpera\u00e7\u00e3o Natal\u201d atraiu o p\u00fablico e bateu o recorde de 50 milh\u00f5es de espectadores em seu fim de semana de estreia.<\/p>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/cidade-brasileira-atrai-turistas-e-supera-nova-york\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/mix.diariodocomercio.com.br\/wp-content\/uploads\/2025\/02\/Nova-York-1140x570.jpg\" data-src=\"https:\/\/mix.diariodocomercio.com.br\/wp-content\/uploads\/2025\/02\/Nova-York-1140x570.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>COMUNICADO<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Cidade brasileira atrai turistas e supera Nova York<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Entrou para o ranking de destinos preferidos para viajar do mundo!<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Confira<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/cidade-brasileira-atrai-turistas-e-supera-nova-york\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/mix.diariodocomercio.com.br\/wp-content\/uploads\/2025\/02\/Nova-York-1140x570.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Cidade brasileira atrai turistas e supera Nova York<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Confira<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Saiba como Dwayne Johnson foi o ator mais bem pago de 2024<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m do filme natalino, Dwayne Johnson tamb\u00e9m estrelou como dublador em \u201cMoana 2\u201d, marcando o seu retorno triunfal para a produ\u00e7\u00e3o, depois de ter sido um sucesso na primeira anima\u00e7\u00e3o. De acordo com os dados revelados, o astro ganhou cerca de US$ 88 milh\u00f5es no ano passado, tornando-se o ator mais bem pago de 2024.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na lista, quem tamb\u00e9m apareceu foi <strong>Ryan Reynolds<\/strong>, que se destacou no ano passado por ter sido produtor principal, co-roteirista e estrela de \u201cDeadpool &amp; Wolverine\u201d. O \u00fanico lan\u00e7amento da Marvel nos cinemas foi um sucesso e encheu os bolsos do ator, que foi recompensado com cerca de US$ 85 milh\u00f5es, apesar dos problemas judiciais que sua esposa Blake Lively, se envolveu por causa de \u201c\u00c9 Assim Que Acaba\u201d, que possui uma s\u00e9rie de pol\u00eamicas nos bastidores.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A revista Forbes revelou um relat\u00f3rio que exp\u00f4s quais foram os atores mais bem pagos de 2024 em Hollywood e quem liderou o ranking foi Dwayne Johnson, apesar do faturamento de um dos filmes que estrelou, n\u00e3o ter alcan\u00e7ado os valores esperados. No ano passado, o ator que tamb\u00e9m \u00e9 conhecido pelo apelido The Rock, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":3443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/3442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=3442"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/3442\/revisions"}],"predecessor-version":[{"id":3444,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/3442\/revisions\/3444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/3443"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=3442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=3442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=3442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}