{"id":34974,"date":"2026-02-10T08:38:23","date_gmt":"2026-02-10T11:38:23","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=34974"},"modified":"2026-02-10T17:29:41","modified_gmt":"2026-02-10T20:29:41","slug":"horario-de-verao-esta-confirmado-para-2026-e-todos-terao-que-avancar-1-hora-no-relogio-em-08-de-marco-neste-pais","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/horario-de-verao-esta-confirmado-para-2026-e-todos-terao-que-avancar-1-hora-no-relogio-em-08-de-marco-neste-pais\/","title":{"rendered":"Hor\u00e1rio de Ver\u00e3o est\u00e1 confirmado para 2026 e todos ter\u00e3o que avan\u00e7ar 1 hora no rel\u00f3gio em 08 de mar\u00e7o neste pa\u00eds"},"content":{"rendered":"\n<p>O Hor\u00e1rio de Ver\u00e3o j\u00e1 tem data marcada para 2026 nos Estados Unidos. No domingo,\u00a0<strong>8 de mar\u00e7o<\/strong>, moradores da maior parte do pa\u00eds dever\u00e3o adiantar os rel\u00f3gios em uma hora, retomando oficialmente o chamado\u00a0<em>daylight saving time<\/em>\u00a0(DST). A medida seguir\u00e1 em vigor at\u00e9\u00a0<strong>1\u00ba de novembro<\/strong>, quando os rel\u00f3gios voltar\u00e3o ao hor\u00e1rio padr\u00e3o.<\/p>\n\n\n\n<p>A mudan\u00e7a acontece sempre no segundo domingo de mar\u00e7o. Nesse dia, os rel\u00f3gios s\u00e3o ajustados uma hora \u00e0 frente, o que reduz o tempo de sono em 60 minutos, mas amplia a luminosidade natural no fim da tarde. Em 2026, por exemplo, o sol passar\u00e1 a nascer por volta das 7h20 e se p\u00f4r ap\u00f3s as 19h em diversas regi\u00f5es do pa\u00eds.<\/p>\n\n\n\n<p>J\u00e1 no primeiro domingo de novembro ocorre o movimento inverso, conhecido como&nbsp;<em>fall back<\/em>, quando os rel\u00f3gios atrasam uma hora e os moradores \u201cganham\u201d mais tempo de sono, com manh\u00e3s mais claras e noites mais curtas.<\/p>\n\n\n\n<p>Atualmente,&nbsp;<strong>48 dos 50 estados americanos<\/strong>&nbsp;adotam o Hor\u00e1rio de Ver\u00e3o. As exce\u00e7\u00f5es s\u00e3o&nbsp;<strong>Hava\u00ed<\/strong>&nbsp;e&nbsp;<strong>Arizona<\/strong>, que mant\u00eam o hor\u00e1rio padr\u00e3o durante todo o ano. Al\u00e9m deles, territ\u00f3rios dos EUA como Porto Rico, Guam, Ilhas Virgens Americanas e Samoa Americana tamb\u00e9m n\u00e3o participam da mudan\u00e7a.<\/p>\n\n\n\n<p>Desde 2005, com a aprova\u00e7\u00e3o do&nbsp;<em>Energy Policy Act<\/em>, o calend\u00e1rio atual est\u00e1 em vigor, determinando o in\u00edcio do Hor\u00e1rio de Ver\u00e3o no segundo domingo de mar\u00e7o e o fim no primeiro domingo de novembro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Debate sobre o fim da mudan\u00e7a de hor\u00e1rio<\/strong><\/h2>\n\n\n\n<p>Apesar da confirma\u00e7\u00e3o para 2026, o futuro do Hor\u00e1rio de Ver\u00e3o segue em debate. Nos \u00faltimos anos, parlamentares e at\u00e9 o presidente Donald Trump j\u00e1 defenderam a ado\u00e7\u00e3o permanente do hor\u00e1rio de ver\u00e3o, eliminando a troca semestral dos rel\u00f3gios. No entanto, nenhuma proposta foi aprovada at\u00e9 agora.<\/p>\n\n\n\n<p>Pesquisas indicam que a maioria dos americanos prefere manter um \u00fanico hor\u00e1rio ao longo do ano, seja o padr\u00e3o ou o de ver\u00e3o. Ainda assim, enquanto n\u00e3o houver mudan\u00e7a na legisla\u00e7\u00e3o federal, a regra continua valendo.<\/p>\n\n\n\n<p>A pr\u00e1tica surgiu durante a&nbsp;<strong>Primeira Guerra Mundial<\/strong>, com o objetivo de economizar energia el\u00e9trica ao aproveitar mais a luz natural. A Alemanha foi o primeiro pa\u00eds a adotar a medida, em 1916, seguida por outras na\u00e7\u00f5es europeias e, em 1918, pelos Estados Unidos.<\/p>\n\n\n\n<p>Desde ent\u00e3o, o Hor\u00e1rio de Ver\u00e3o passou por idas e vindas, per\u00edodos de suspens\u00e3o e ajustes no calend\u00e1rio, at\u00e9 chegar ao modelo atual. Mesmo mais de um s\u00e9culo depois, a simples mudan\u00e7a de uma hora no rel\u00f3gio segue gerando debates sobre seus reais benef\u00edcios para a economia, a sa\u00fade e a rotina da popula\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Hor\u00e1rio de Ver\u00e3o j\u00e1 tem data marcada para 2026 nos Estados Unidos. No domingo,\u00a08 de mar\u00e7o, moradores da maior parte do pa\u00eds dever\u00e3o adiantar os rel\u00f3gios em uma hora, retomando oficialmente o chamado\u00a0daylight saving time\u00a0(DST). A medida seguir\u00e1 em vigor at\u00e9\u00a01\u00ba de novembro, quando os rel\u00f3gios voltar\u00e3o ao hor\u00e1rio padr\u00e3o. A mudan\u00e7a acontece sempre [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":34978,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-34974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/34974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=34974"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/34974\/revisions"}],"predecessor-version":[{"id":34979,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/34974\/revisions\/34979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/34978"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=34974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=34974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=34974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}