{"id":3662,"date":"2025-03-12T18:18:22","date_gmt":"2025-03-12T21:18:22","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=3662"},"modified":"2025-03-12T18:18:24","modified_gmt":"2025-03-12T21:18:24","slug":"nasa-envia-4-astronautas-ao-espaco-e-vai-transmitir-tudo-saiba-como-assistir","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/nasa-envia-4-astronautas-ao-espaco-e-vai-transmitir-tudo-saiba-como-assistir\/","title":{"rendered":"Nasa envia 4 astronautas ao espa\u00e7o e vai transmitir tudo: Saiba como assistir"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Na noite desta quarta-feira (12\/03), ser\u00e1 poss\u00edvel atrav\u00e9s do Youtube ver ao vivo a transmiss\u00e3o da decolagem da miss\u00e3o Crew-10 da SpaceX, diretamente do Centro Espacial Kennedy da Nasa, na Fl\u00f3rida, nos Estados Unidos. Ser\u00e3o enviados quatro astronautas com destino a Esta\u00e7\u00e3o Espacial Internacional (ISS), atrav\u00e9s da nave Crew Dragon. Quem quiser conferir esse evento astron\u00e1utico, poder\u00e1 assistir a partir das 20h48 (hor\u00e1rio de Bras\u00edlia), no perfil oficial da Nasa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A previs\u00e3o de chegada \u00e9 na quinta-feira (13) \u00e0s 7h (hor\u00e1rio de Bras\u00edlia) e quando a nave espacial estiver no local, o evento tamb\u00e9m ser\u00e1 transmitido pela ag\u00eancia norte-americana, a partir das 5h15 (hor\u00e1rio de Bras\u00edlia). Os astronautas s\u00e3o: Anne McClain,Takuya Onishi, Nichole Ayers e Kirill Peskov com o objetivo de render a Starliner, no qual est\u00e3o Butch Wilmore e Suni Williams, que ainda n\u00e3o conseguiram retornar para a Terra.&nbsp;<\/p>\n\n\n\n \n \t\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/cidade-brasileira-atrai-turistas-e-supera-nova-york\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/mix.diariodocomercio.com.br\/wp-content\/uploads\/2025\/02\/Nova-York-1140x570.jpg\" data-src=\"https:\/\/mix.diariodocomercio.com.br\/wp-content\/uploads\/2025\/02\/Nova-York-1140x570.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>COMUNICADO<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Cidade brasileira atrai turistas e supera Nova York<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Entrou para o ranking de destinos preferidos para viajar do mundo!<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Confira<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/cidade-brasileira-atrai-turistas-e-supera-nova-york\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/mix.diariodocomercio.com.br\/wp-content\/uploads\/2025\/02\/Nova-York-1140x570.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Cidade brasileira atrai turistas e supera Nova York<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Confira<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n\n\n\n<h2 class=\"wp-block-heading\">O que aconteceu com Butch Wilmore e Suni Williams?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">No dia 5 de junho de 2024, Butch Wilmore e Suni Williams foram aviados atrav\u00e9s da espa\u00e7onave Starliner da Boeing para uma miss\u00e3o, mas por causa de alguns problemas na nave, a miss\u00e3o precisou ser estendida e a dupla de astronautas ficaram presos no espa\u00e7o, chamando a aten\u00e7\u00e3o do mundo todo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inclusive, o tempo que Wilmore e Williams est\u00e3o no espa\u00e7o se tornou pauta pol\u00edtica, pois o presidente Donald Trump e seu conselheiro pr\u00f3ximo Elon Musk acusaram o ex-presidente Joe Biden de abandonar a dupla. Vale ressaltar que Musk \u00e9 chefe da SpaceX e chegou a dizer, sem provas, de que havia oferecido a Biden uma miss\u00e3o de &#8220;resgate&#8221; fora das rota\u00e7\u00f5es de rotina da tripula\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar desses conflitos pol\u00edticos, a Nasa quer que os tripulantes retornem o mais r\u00e1pido poss\u00edvel, depois de nove meses em microgravidade e caminhadas espaciais. Com tudo ocorrendo bem, eles estar\u00e3o de volta \u00e0 Terra no dia 19 de mar\u00e7o.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite desta quarta-feira (12\/03), ser\u00e1 poss\u00edvel atrav\u00e9s do Youtube ver ao vivo a transmiss\u00e3o da decolagem da miss\u00e3o Crew-10 da SpaceX, diretamente do Centro Espacial Kennedy da Nasa, na Fl\u00f3rida, nos Estados Unidos. Ser\u00e3o enviados quatro astronautas com destino a Esta\u00e7\u00e3o Espacial Internacional (ISS), atrav\u00e9s da nave Crew Dragon. Quem quiser conferir esse evento [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":3663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/3662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=3662"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/3662\/revisions"}],"predecessor-version":[{"id":3664,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/3662\/revisions\/3664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/3663"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=3662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=3662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=3662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}