{"id":3836,"date":"2025-03-17T10:38:39","date_gmt":"2025-03-17T13:38:39","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=3836"},"modified":"2025-03-17T10:38:42","modified_gmt":"2025-03-17T13:38:42","slug":"elon-musk-prepara-viagem-para-colonizar-marte-veja-se-voce-pode-se-candidatar","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/elon-musk-prepara-viagem-para-colonizar-marte-veja-se-voce-pode-se-candidatar\/","title":{"rendered":"Elon Musk prepara viagem para colonizar Marte. Veja se voc\u00ea pode se candidatar!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No ano passado, o bilion\u00e1rio Elon Musk, dono da Tesla e da SpaceX (entre outras empresas), anunciou que pretende colonizar Marte. O empres\u00e1rio afirmou que pretende enviar milh\u00f5es de pessoas para o planeta vermelho e &#8220;come\u00e7ar uma vida multi planet\u00e1ria&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Musk, todos os projetos da SpaceX &#8211; Falcon, Dragon, Starlink, e Starship &#8211; v\u00e3o desenvolver tecnologias para possibilitar o envio de humanos para Marte. Um dos pontos \u00e9 que as naves precisam ser reutiliz\u00e1veis, conseguindo voltar para a Terra depois de levarem pessoas e suprimentos. <em>\u201cO objetivo da SpaceX \u00e9 desenvolver as tecnologias necess\u00e1rias para tornar a vida multiplanet\u00e1ria. Esta \u00e9 a primeira vez na hist\u00f3ria de 4 bilh\u00f5es de anos da Terra em que \u00e9 poss\u00edvel realizar esse objetivo\u201d<\/em>, afirmou comunicado da empresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas por que Marte e n\u00e3o a Lua, que est\u00e1 bem mais perto? Musk explicou que o planeta vizinho tem mais recursos, que diminuiriam a necessidade de fazer constantes viagens para a Terra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a exame, antes de enviar seres humanos, a SpaceX vai mandar cinco naves espaciais para o planeta vermelho at\u00e9 2026. Se todas pousarem em seguran\u00e7a, as miss\u00f5es tripuladas seriam poss\u00edveis em quatro anos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como se candidatar para a viagem a Marte?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Calma, ainda n\u00e3o existem inscri\u00e7\u00f5es para volunt\u00e1rios e a empresa n\u00e3o divulgou crit\u00e9rios para os tripulantes. O mais prov\u00e1vel \u00e9 que, pelo menos as primeiras miss\u00f5es, sejam apenas para profissionais da \u00e1rea, astronautas que j\u00e1 tenham experi\u00eancia com viagens espaciais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De qualquer forma, ainda temos que esperar, no m\u00ednimo, quatro anos.<\/p>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/nasa-envia-4-astronautas-ao-espaco-e-vai-transmitir-tudo-saiba-como-assistir\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/03\/NASA.jpg\" data-src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/03\/NASA.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>ESPA\u00c7O<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Nasa envia 4 astronautas ao espa\u00e7o e vai transmitir tudo: Saiba como assistir<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Na noite desta quarta-feira (12\/03), ser\u00e1 poss\u00edvel atrav\u00e9s do Youtube ver ao vivo a transmiss\u00e3o da decolagem da miss\u00e3o Crew-10 da SpaceX, diretamente do Centro Espacial Kennedy da Nasa, na Fl\u00f3rida, nos\u2026<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Leia mais<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/nasa-envia-4-astronautas-ao-espaco-e-vai-transmitir-tudo-saiba-como-assistir\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2025\/03\/NASA.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Nasa envia 4 astronautas ao espa\u00e7o e vai transmitir tudo: Saiba como assistir<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Leia mais<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>O bilion\u00e1rio Elon Musk j\u00e1 anunciou que pretende enviar miss\u00f5es com tripulantes para &#8220;colonizar Marte&#8221; e &#8220;come\u00e7ar uma vida multi planet\u00e1ria&#8221;.<\/p>\n","protected":false},"author":6,"featured_media":3838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/3836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=3836"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/3836\/revisions"}],"predecessor-version":[{"id":3839,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/3836\/revisions\/3839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/3838"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=3836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=3836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=3836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}