{"id":39937,"date":"2026-03-28T09:25:00","date_gmt":"2026-03-28T12:25:00","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=39937"},"modified":"2026-03-27T09:53:07","modified_gmt":"2026-03-27T12:53:07","slug":"inss-em-dobro-vai-salvar-a-vida-de-aposentados-nos-proximos-meses-e-pagamento-podera-ultrapassar-r-25-mil","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/inss-em-dobro-vai-salvar-a-vida-de-aposentados-nos-proximos-meses-e-pagamento-podera-ultrapassar-r-25-mil\/","title":{"rendered":"INSS em dobro vai salvar a vida de aposentados nos pr\u00f3ximos meses e pagamento poder\u00e1 ultrapassar R$ 25 mil"},"content":{"rendered":"\n<p>Se voc\u00ea \u00e9 aposentado ou pensionista do INSS (Instituto Nacional do Seguro Social), temos uma boa not\u00edcia para voc\u00ea. Nos pr\u00f3ximos dois meses, o seu benef\u00edcio pago pelo instituto vai vir mais alto do que o comum! O INSS confirmou a antecipa\u00e7\u00e3o do 13\u00ba sal\u00e1rio para o primeiro semestre desse ano (como j\u00e1 se tornou padr\u00e3o no instituto). O valor ser\u00e1 pago em duas parcelas, a primeira em abril e a segunda em maio.<\/p>\n\n\n\n<p>Para quem recebe o teto do INSS, que \u00e9 de R$ 8.475,55 em 2026, pode receber quase R$ 25 mil somando os dois meses do benef\u00edcio mais as duas parcelas do 13\u00ba.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Confira o calend\u00e1rio de pagamento do 13\u00ba sal\u00e1rio do INSS em 2026:<\/h2>\n\n\n\n<p><strong>Para quem recebe at\u00e9 um sal\u00e1rio m\u00ednimo<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-left\" data-align=\"left\"><strong>Final do n\u00famero do benef\u00edcio<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>1\u00aa parcela<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>2\u00aa parcela<\/strong><\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">1<\/td><td class=\"has-text-align-left\" data-align=\"left\">24 de abril<\/td><td class=\"has-text-align-left\" data-align=\"left\">25 de maio<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">2<\/td><td class=\"has-text-align-left\" data-align=\"left\">27 de abril<\/td><td class=\"has-text-align-left\" data-align=\"left\">26 de maio<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">3<\/td><td class=\"has-text-align-left\" data-align=\"left\">28 de abril<\/td><td class=\"has-text-align-left\" data-align=\"left\">27 de maio<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">4<\/td><td class=\"has-text-align-left\" data-align=\"left\">29 de abril<\/td><td class=\"has-text-align-left\" data-align=\"left\">28 de maio<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">5<\/td><td class=\"has-text-align-left\" data-align=\"left\">30 de abril<\/td><td class=\"has-text-align-left\" data-align=\"left\">29 de maio<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">6<\/td><td class=\"has-text-align-left\" data-align=\"left\">4 de maio<\/td><td class=\"has-text-align-left\" data-align=\"left\">1 de junho<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">7<\/td><td class=\"has-text-align-left\" data-align=\"left\">5 de maio<\/td><td class=\"has-text-align-left\" data-align=\"left\">2 de junho<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">8<\/td><td class=\"has-text-align-left\" data-align=\"left\">6 de maio<\/td><td class=\"has-text-align-left\" data-align=\"left\">3 de junho<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">9<\/td><td class=\"has-text-align-left\" data-align=\"left\">7 de maio<\/td><td class=\"has-text-align-left\" data-align=\"left\">5 de junho<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">0<\/td><td class=\"has-text-align-left\" data-align=\"left\">8 de maio<\/td><td class=\"has-text-align-left\" data-align=\"left\">8 de junho<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Para quem recebe mais de um sal\u00e1rio m\u00ednimo<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-left\" data-align=\"left\"><strong>Final do n\u00famero do benef\u00edcio<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>1\u00aa parcela<\/strong><\/td><td class=\"has-text-align-left\" data-align=\"left\"><strong>2\u00aa parcela<\/strong><\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">1 e 6<\/td><td class=\"has-text-align-left\" data-align=\"left\">4 de maio<\/td><td class=\"has-text-align-left\" data-align=\"left\">1 de junho<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">2 e 7<\/td><td class=\"has-text-align-left\" data-align=\"left\">5 de maio<\/td><td class=\"has-text-align-left\" data-align=\"left\">2 de junho<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">3 e 8<\/td><td class=\"has-text-align-left\" data-align=\"left\">6 de maio<\/td><td class=\"has-text-align-left\" data-align=\"left\">3 de junho<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">4 e 9<\/td><td class=\"has-text-align-left\" data-align=\"left\">7 de maio<\/td><td class=\"has-text-align-left\" data-align=\"left\">5 de junho<\/td><\/tr><tr><td class=\"has-text-align-left\" data-align=\"left\">5 e 0<\/td><td class=\"has-text-align-left\" data-align=\"left\">8 de maio<\/td><td class=\"has-text-align-left\" data-align=\"left\">8 de junho<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/a-partir-de-quantos-anos-e-indicado-criancas-praticarem-musculacao\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/03\/crianca-levantando-peso.jpg\" data-src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/03\/crianca-levantando-peso.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>SA\u00daDE<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>A partir de quantos anos \u00e9 indicado crian\u00e7as praticarem muscula\u00e7\u00e3o?<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>Existe um senso comum de que crian\u00e7as praticarem muscula\u00e7\u00e3o pode prejudicar o desenvolvimento delas, mas ser\u00e1 que ele tem base \u2026<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Leia mais<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/a-partir-de-quantos-anos-e-indicado-criancas-praticarem-musculacao\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/03\/crianca-levantando-peso.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>A partir de quantos anos \u00e9 indicado crian\u00e7as praticarem muscula\u00e7\u00e3o?<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Leia mais<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se voc\u00ea \u00e9 aposentado ou pensionista do INSS (Instituto Nacional do Seguro Social), temos uma boa not\u00edcia para voc\u00ea. Nos pr\u00f3ximos dois meses, o seu benef\u00edcio pago pelo instituto vai vir mais alto do que o comum! O INSS confirmou a antecipa\u00e7\u00e3o do 13\u00ba sal\u00e1rio para o primeiro semestre desse ano (como j\u00e1 se tornou [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":39938,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/39937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=39937"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/39937\/revisions"}],"predecessor-version":[{"id":39941,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/39937\/revisions\/39941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/39938"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=39937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=39937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=39937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}