{"id":45044,"date":"2026-05-13T16:53:01","date_gmt":"2026-05-13T19:53:01","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=45044"},"modified":"2026-05-13T16:53:04","modified_gmt":"2026-05-13T19:53:04","slug":"governo-vai-dar-desconto-na-gasolina-durante-60-dias-para-brasileiros","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/governo-vai-dar-desconto-na-gasolina-durante-60-dias-para-brasileiros\/","title":{"rendered":"Governo vai dar desconto na gasolina durante 60 dias para brasileiros"},"content":{"rendered":"\n<p>Na \u00faltima quarta-feira (13), o governo federal anunciou mais uma medida provis\u00f3ria (MP) para tentar conter a alta no pre\u00e7o dos combust\u00edveis, como a gasolina e o diesel, sejam produzidos no Brasil ou importados. A MP estabelece um benef\u00edcio tribut\u00e1rio em dois tributos federais que incidem sobre combust\u00edveis: o PIS\/Cofins e a Cide.<\/p>\n\n\n\n<p>A nova subven\u00e7\u00e3o vai come\u00e7ar pela gasolina, que ainda n\u00e3o tinha sido alvo de nenhuma medida do governo para tentar controlar seu pre\u00e7o. Segundo o g1, o governo afirma que a medida pode se estender tamb\u00e9m ao diesel. Mas o desconto tem seus limites e n\u00e3o vai poder passar do teto dos tributos federais, que atualmente s\u00e3o de:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>R$ 0,89 por litro na gasolina, o que inclui PIS\/Cofins e Cide; e<\/li>\n\n\n\n<li>R$ 0,35 de PIS\/Cofins por litro de \u00f3leo diesel.*<\/li>\n<\/ul>\n\n\n\n<p>*No caso do diesel, j\u00e1 havia uma MP que havia suspendido a tributa\u00e7\u00e3o do combust\u00edvel, mas ela deixa de ser aplicada este m\u00eas, que \u00e9 quando essa nova MP entra em vigor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Medida do governo deve ter impacto de at\u00e9 R$ 1,2 bilh\u00e3o por m\u00eas<\/h2>\n\n\n\n<p>De acordo com o ministro do Planejamento e Or\u00e7amento, Bruno Moretti, a medida n\u00e3o vai pressionar os cofres p\u00fablicos, apesar do impacto estimado entre R$ 1 bilh\u00e3o e R$ 1,2 bilh\u00e3o por m\u00eas. Os valores exatos da subven\u00e7\u00e3o ser\u00e3o divulgados nos pr\u00f3ximos dias. Para gasolina, Moretti estima que o valor deve ficar entre R$ 0,40 e R$ 0,45 por litro e R$ 0,35 por litro do diesel.<\/p>\n\n\n\n<p><em>&#8220;Como a receita da Uni\u00e3o por meio de dividendos, royalties e participa\u00e7\u00e3o tem crescido com o aumento da cota\u00e7\u00e3o do petr\u00f3leo no mercado internacional, a medida ser\u00e1 neutra do ponto de vista fiscal&#8221;<\/em>, justificou o governo.<\/p>\n\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/brasil-deve-abrir-as-portas-para-novas-companhias-aereas-estrangeiras-em-2026\/\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/05\/aviao.jpg\" data-src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/05\/aviao.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>AVIA\u00c7\u00c3O<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span>Brasil deve abrir as portas para novas companhias a\u00e9reas estrangeiras em 2026<\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>O governo federal est\u00e1 se planejando para permitir que companhias a\u00e9reas de outros pa\u00edses da Am\u00e9rica do Sul possam oferecer \u2026<\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Leia mais<\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/brasil-deve-abrir-as-portas-para-novas-companhias-aereas-estrangeiras-em-2026\/\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/05\/aviao.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span>Brasil deve abrir as portas para novas companhias a\u00e9reas estrangeiras em 2026<\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Leia mais<\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima quarta-feira (13), o governo federal anunciou mais uma medida provis\u00f3ria (MP) para tentar conter a alta no pre\u00e7o dos combust\u00edveis, como a gasolina e o diesel, sejam produzidos no Brasil ou importados. A MP estabelece um benef\u00edcio tribut\u00e1rio em dois tributos federais que incidem sobre combust\u00edveis: o PIS\/Cofins e a Cide. A nova [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-45044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/45044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=45044"}],"version-history":[{"count":1,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/45044\/revisions"}],"predecessor-version":[{"id":45045,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/45044\/revisions\/45045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/4028"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=45044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=45044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=45044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}