{"id":51895,"date":"2026-07-15T16:54:00","date_gmt":"2026-07-15T19:54:00","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=51895"},"modified":"2026-07-15T10:10:51","modified_gmt":"2026-07-15T13:10:51","slug":"nova-lei-aprovada-vai-enviar-alimentos-para-a-casa-de-mulheres-vitimas-de-violencia-domestica-no-brasil","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/nova-lei-aprovada-vai-enviar-alimentos-para-a-casa-de-mulheres-vitimas-de-violencia-domestica-no-brasil\/","title":{"rendered":"Nova lei aprovada vai enviar alimentos para a casa de mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica no Brasil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Sistema Nacional de Seguran\u00e7a Alimentar e Nutricional (Sisan) faz parte de a\u00e7\u00f5es dos governos federal, estaduais e municipais para garantir o direito \u00e0 alimenta\u00e7\u00e3o. sancionada no final de junho a Lei 15.451\/2026 altera esse sistema, estabelecendo prioridade no abastecimento de alimentos para servi\u00e7os de acolhimento de v\u00edtimas de viol\u00eancia dom\u00e9stica, medida que busca favorecer a articula\u00e7\u00e3o entre pol\u00edticas de Seguran\u00e7a Alimentar e servi\u00e7os de prote\u00e7\u00e3o \u00e0s mulheres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Ag\u00eancia CNM (Confedera\u00e7\u00e3o Nacional de Munic\u00edpios) de Not\u00edcias, com essa altera\u00e7\u00e3o, a distribui\u00e7\u00e3o de alimentos no \u00e2mbito do Sisan passa a priorizar equipamentos que realizam acolhimento e prote\u00e7\u00e3o de mulheres em situa\u00e7\u00e3o de viol\u00eancia, incluindo casas-abrigo e centros de atendimento integral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Por fim, a entidade ressalta que o acesso \u00e0 alimenta\u00e7\u00e3o adequada \u00e9 essencial na prote\u00e7\u00e3o das mulheres acolhidas e seus dependentes, contribuindo para o atendimento de necessidades b\u00e1sicas durante o per\u00edodo de acolhimento e reconstru\u00e7\u00e3o de autonomia&#8221;<\/em>, explica a ag\u00eancia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">61% das v\u00edtimas de viol\u00eancia n\u00e3o denunciam agress\u00f5es por causa de depend\u00eancia financeira<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lembrando que muitas v\u00edtimas de viol\u00eancia dom\u00e9stica tamb\u00e9m s\u00e3o dependentes financeiramente de seus agressores, ficando sem condi\u00e7\u00f5es de se sustentarem ap\u00f3s o fim do relacionamento. Estabelecimentos que acolhem essas v\u00edtimas, junto com seus dependentes, como filhos, oferecem um apoio enquanto elas tentam criar essa independ\u00eancia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo uma pesquisa desenvolvida pela doutoranda em psicologia cl\u00ednica e cultura da Universidade de Bras\u00edlia (UnB) Carolina Campos Afonso, servidora do Tribunal de Justi\u00e7a do Distrito Federal e dos Territ\u00f3rios (TJDFT), 61% das mulheres afirmam que a depend\u00eancia financeira \u00e9 o que impede que elas denunciem as agress\u00f5es. <\/p>\n\n\n<style>@media (min-width: 992px) {\n    .recomendadorV2Area1 {\n        width: 280px;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n        width: calc(100% - 280px);\n    }\n}\n\n@media (max-width: 992px) {\n    .recomendadorV2Button {\n        margin: 0 auto;\n    }\n    .recomendadorV2Area {\n        flex-direction: column;\n        text-align: center;\n    }\n    .recomendadorV2Area2 {\n        padding: 0px 20px;\n    }\n}\n\n.recomendadorV2Area {\n    background: #eeeeee3d;\n    border-radius: 10px;\n    padding: 15px;\n    display: flex;\n    margin: 15px auto;\n    border: 1px solid #00000014;\n    max-width: 800px;\n}\n\n.recomendadorV2Area1 img {\n    width: 280px;\n    height: auto;\n    border-radius: 8px;\n}\n\n.linkrecomendadorv2 {\n    text-decoration: none !important;\n}\n\n.recomendadorV2Area2 .recomendadorV2Type {\n    text-transform: uppercase;\n    font-weight: 500;\n    font-size: 11px;\n    letter-spacing: 2px;\n    color: #666;\n    margin: 12px 0;\n    display: block;\n}\n\n.recomendadorV2Title h2 {\n    padding-top: 0px !important;\n    margin: 0px !important;\n    border-left: none !important;\n    padding-left: 0px !important;\n    line-height: 1.3;\n    color: #000 !important;\n    font-size: 24px;\n    margin-bottom: 12px !important;\n}\n\n.recomendadorV2Desc {\n    color: #333;\n    margin: 12px 0px !important;\n    font-size: 15px;\n    line-height: 1.5;\n}\n\n.recomendadorV2Button {\n    width: auto;\n    max-width: 200px;\n    margin: 0;\n    display: inline-flex;\n    align-items: center;\n    background: #1D3557;\n    border-radius: 8px;\n    color: #fff;\n    height: 36px;\n    justify-content: center;\n    text-align: center;\n    font-size: 14px;\n    padding: 0 20px;\n    transition: background-color 0.2s ease;\n}\n\n.recomendadorV2Button:hover {\n    background: #2a4d7a;\n}\n\n.recomendadorV2Button:after {\n    margin-top: -2px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 8px;\n}\n\n.recomendadorV2Alert {\n    text-align: left;\n    font-size: 11px;\n    margin-top: 8px;\n    color: #666;\n}\n\n.recomendadorFixedArea {\n    width: 100%;\n    display: flex;\n    justify-content: center;\n    align-items: center;\n}\n\n@media (min-width: 992px) {\n    #recomendadorFixed {\n        width: 32% !important;\n        left: 5%;\n    }\n    .recomendadorCloseFixed{\n        right: inherit !important;\n        left: 378px !important;\n    }\n}\n\n#recomendadorFixed {\n    width: 90%;\n    box-shadow: 0 10px 20px 0px #00000057;\n    display: none;\n    height: 90px;\n    background: #F6F6F6;\n    position: fixed;\n    flex-direction: row;\n    bottom: 10px;\n    z-index: 9999;\n    border-radius: 16px;\n    padding: 7px 10px;\n}\n\n.recomendadorLeftArea {\n    width: 160px;\n}\n\n.recomendadorRightArea h2 {\n    padding-top: 0px;\n    margin: 2px 0px 4px 0px !important;\n    font-weight: 400;\n    text-align: center;\n    padding-left: 0px !important;\n    color: #000 !important;\n    border-left: none !important;\n    line-height: 20px;\n    font-size: 12px !important;\n}\n\n.recomendadorImgFixed {\n    overflow: hidden;\n    padding: 8px 6px;\n    height: 100%;\n}\n\n.recomendadorImgFixed img {\n    height: 100% !important;\n    border-radius: 16px;\n}\n\n.recomendadorRightArea {\n    padding-top: 6px;\n    display: flex;\n    width: calc(100% - 130px);\n    justify-content: space-between;\n    align-items: center;\n    flex-direction: column;\n}\n\n.recomendadorButtonFixed {\n    margin: 0 auto;\n    background: #1D3557;\n    width: 80%;\n    text-align: center;\n    font-size: 10px;\n    color: #FFF;\n    padding: 2px 10px;\n    border-radius: 3px;\n}\n\n.recomendadorButtonFixed:after {\n    margin-top: -3px;\n    content: \"\u2192\";\n    padding: 0px 0px 0px 10px;\n}\n\n.recomendadorAlertFixed {\n    font-weight: 400;\n    text-align: center;\n    color: #484848;\n    font-size: 8px;\n}\n\n.recomendadorCloseFixed {\n    z-index: 99999;\n    display: none;\n    right: 0px;\n    left: inherit;\n    bottom: 99px;\n    position: fixed;\n    justify-content: center;\n    background: #F6F6F6;\n    width: 25px;\n    align-items: center;\n    height: 25px;\n    font-weight: 800;\n    border-radius: 50%;\n    border: 1px solid #EBEBEB;\n}\n\n.recomendadorV2Desc{\n    color: #000000;\n    margin: 20px 0px;\n}\n\n@media (max-width: 576px) {\n    .recomendadorV2Area {\n      padding: 10px;\n      max-width: 100%;\n    }\n  \n    .recomendadorV2Area1 img {\n      width: 100%;\n      border-radius: 6px;\n    }\n  \n    .recomendadorV2Area2 .recomendadorV2Type {\n      font-size: 9px;\n      letter-spacing: 1px;\n      margin: 8px 0;\n    }\n  \n    .recomendadorV2Title h2 {\n      font-size: 18px !important;\n      margin-bottom: 8px !important;\n      line-height: 1.2;\n    }\n  \n    .recomendadorV2Desc {\n      font-size: 14px;\n      margin: 8px 0 !important;\n      line-height: 1.4;\n    }\n  \n    .recomendadorV2Button {\n      font-size: 14px;\n      height: 40px;\n      padding: 0 12px;\n      max-width: 100%;\n      width: 100%;\n    }\n  \n    .recomendadorV2Button:after {\n      padding-left: 6px;\n    }\n  }\n  <\/style>\n        <div class=\"lazyblock-recomendador-v2-2jDGz wp-block-lazyblock-recomendador-v2\">\n        <a class=\"linkrecomendadorv2\" href=\"https:\/\/diariodocomercio.com.br\/mix\/apos-anos-sem-aceitar-dinheiro-pais-volta-atras-e-obriga-comercio-a-receber-notas-e-moedas\/#google_vignette%20\">\n            <div class=\"recomendadorV2Area\">\n            <div class=\"recomendadorV2Area1\">\n                <div class=\"recomendadorV2Img\">\n                <img class=\"lazyloaded\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/04\/dinheiro-750x375.jpg\" data-src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/04\/dinheiro-750x375.jpg\" alt=\"\">\n                <\/div>\n            <\/div>\n            <div class=\"recomendadorV2Area2\">\n                <div class=\"recomendadorV2Type\">\n                    <span>MUNDO t\u00edtulo=Ap\u00f3s anos sem aceitar dinheiro, pa\u00eds volta atr\u00e1s e obriga com\u00e9rcio a receber notas e moedas <\/span>\n                <\/div>\n                <div class=\"recomendadorV2Title\">\n                <h2><span><\/span><\/h2>\n                <\/div>\n                <div class=\"recomendadorV2Desc\">\n                <span>A Su\u00e9cia foi um dos primeiros pa\u00edses a apostar forte na digitaliza\u00e7\u00e3o da sua economia, com o dinheiro vivo se \u2026 <\/span>\n                <\/div>\n                <div class=\"recomendadorV2Button\">Leia mais <\/div>\n                <div class=\"recomendadorV2Alert\"><\/div>\n            <\/div>\n            <\/div>\n        <\/a>\n        <div>\n            <div style=\"z-index:99999;\" id=\"buttonClose\" onclick=\"closeRecomendadorFixed()\">\n            <div class=\"recomendadorCloseFixed\">X<\/div>\n            <\/div>\n            <a href=\"https:\/\/diariodocomercio.com.br\/mix\/apos-anos-sem-aceitar-dinheiro-pais-volta-atras-e-obriga-comercio-a-receber-notas-e-moedas\/#google_vignette%20\">\n            <div class=\"recomendadorFixedArea\">\n                <div id=\"recomendadorFixed\">\n                <div class=\"recomendadorLeftArea\">\n                    <div class=\"recomendadorImgFixed\">\n                    <img class=\"lazyload\" decoding=\"async\" src=\"https:\/\/diariodocomercio.com.br\/mix\/wp-content\/uploads\/2026\/04\/dinheiro-750x375.jpg\" alt=\"\">\n                    <\/div>\n                <\/div>\n                <div class=\"recomendadorRightArea\">\n                    <div class=\"recomendadorTitleFixed\">\n                    <h2><span><\/span><\/h2>\n                    <\/div>\n                    <div class=\"recomendadorButtonFixed\">Leia mais <\/div>\n                    <div class=\"recomendadorAlertFixed\"><\/div>\n                <\/div>\n                <\/div>\n            <\/div>\n            <\/a>\n        <\/div>\n        <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma lei sancionada no fim de junho estabelece que o Sisan deve priorizar o abastecimento de estabelecimentos para v\u00edtimas de viol\u00eancia.<\/p>\n","protected":false},"author":6,"featured_media":40366,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-51895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/51895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=51895"}],"version-history":[{"count":2,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/51895\/revisions"}],"predecessor-version":[{"id":51899,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/51895\/revisions\/51899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/40366"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=51895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=51895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=51895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}