{"id":7022,"date":"2025-05-11T20:27:00","date_gmt":"2025-05-11T23:27:00","guid":{"rendered":"https:\/\/diariodocomercio.com.br\/mix\/?p=7022"},"modified":"2025-05-09T14:07:18","modified_gmt":"2025-05-09T17:07:18","slug":"celso-portiolli-avisa-o-sbt-e-assina-com-emissora-de-tv-concorrente","status":"publish","type":"post","link":"https:\/\/diariodocomercio.com.br\/mix\/celso-portiolli-avisa-o-sbt-e-assina-com-emissora-de-tv-concorrente\/","title":{"rendered":"Celso Portiolli avisa o SBT e assina com emissora de TV concorrente"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O apresentador Celso Portiolli, um dos maiores nomes da televis\u00e3o brasileira e atual comandante do Domingo Legal, no SBT, acaba de dar um passo ousado em sua carreira. Aos 57 anos, ele anunciou nesta quarta-feira (7) um acordo com a plataforma de streaming Zapping, concorrente direta da TV tradicional \u2014 incluindo a pr\u00f3pria emissora em que trabalha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo informa\u00e7\u00f5es confirmadas pelo colunista Gabriel Vaquer, do F5, da Folha de S.Paulo, Portiolli se torna acionista e embaixador oficial da Zapping, refor\u00e7ando seu nome n\u00e3o apenas como apresentador, mas tamb\u00e9m como investidor e figura estrat\u00e9gica no setor de m\u00eddia digital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEu invisto no que eu acredito, e eu realmente acredito que a <a href=\"https:\/\/www.zapping.com.br\/\" target=\"_blank\" rel=\"noopener\"><strong>Zapping <\/strong><\/a>\u00e9 o futuro da TV\u201d<\/em>, afirmou Portiolli em entrevista. O acordo, que teria levado cerca de seis meses para ser fechado, marca uma guinada importante na trajet\u00f3ria do apresentador \u2014 que, apesar de manter seu contrato com o SBT, agora tamb\u00e9m atua diretamente com uma plataforma que exibe canais abertos, pagos e eventos esportivos ao vivo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Repercuss\u00e3o no mercado<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A chegada de Portiolli \u00e9 vista como uma jogada estrat\u00e9gica por parte da Zapping. \u201cA presen\u00e7a dele refor\u00e7a nosso compromisso de oferecer uma TV sem burocracias, com foco na experi\u00eancia do usu\u00e1rio\u201d, afirmou Chico Vargas, executivo da empresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Zapping chegou ao Brasil em 2023 e atua como uma plataforma h\u00edbrida entre TV por assinatura e streaming, oferecendo uma navega\u00e7\u00e3o mais intuitiva e digitalizada do que os modelos tradicionais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>E o SBT?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 o momento, n\u00e3o h\u00e1 informa\u00e7\u00f5es oficiais sobre qualquer rompimento entre Portiolli e o SBT. Fontes ligadas \u00e0 emissora afirmam que o contrato com o Domingo Legal permanece inalterado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, o envolvimento com uma concorrente direta \u2014 que disputa a aten\u00e7\u00e3o do p\u00fablico e o espa\u00e7o publicit\u00e1rio \u2014 pode gerar tens\u00f5es nos bastidores, especialmente se o apresentador passar a promover ativamente o novo servi\u00e7o dentro de suas redes sociais ou em apari\u00e7\u00f5es p\u00fablicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portiolli, que j\u00e1 \u00e9 conhecido por seu tino comercial, parece agora consolidar uma nova fase de sua carreira: a de empres\u00e1rio e influenciador do futuro da televis\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O apresentador Celso Portiolli, um dos maiores nomes da televis\u00e3o brasileira e atual comandante do Domingo Legal, no SBT, acaba de dar um passo ousado em sua carreira. Aos 57 anos, ele anunciou nesta quarta-feira (7) um acordo com a plataforma de streaming Zapping, concorrente direta da TV tradicional \u2014 incluindo a pr\u00f3pria emissora em [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":7023,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_post_split":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_referencia":"","_links":{"self":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/7022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/comments?post=7022"}],"version-history":[{"count":2,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/7022\/revisions"}],"predecessor-version":[{"id":7025,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/posts\/7022\/revisions\/7025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media\/7023"}],"wp:attachment":[{"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/media?parent=7022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/categories?post=7022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodocomercio.com.br\/mix\/wp-json\/wp\/v2\/tags?post=7022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}